{"id":1619,"date":"2024-01-30T12:06:55","date_gmt":"2024-01-30T12:06:55","guid":{"rendered":"https:\/\/twind.io\/co\/?p=1619"},"modified":"2024-01-30T12:06:57","modified_gmt":"2024-01-30T12:06:57","slug":"sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo","status":"publish","type":"post","link":"https:\/\/twind.io\/co\/blog\/prl\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\/","title":{"rendered":"SST: Entendiendo la Seguridad y Salud en el Trabajo en Colombia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En el mundo laboral de Colombia, la&nbsp;<strong>SST<\/strong>&nbsp;o&nbsp;<strong>Seguridad y Salud en el Trabajo<\/strong>&nbsp;es un t\u00e9rmino de gran importancia. Este art\u00edculo te va a dar el dato completo de lo que significa la SST, su objetivo principal de garantizar un ambiente laboral seguro y saludable, los servicios que presta para lograr este objetivo y qui\u00e9n es el encargado de ponerle la lupa a la SST en Colombia.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Tabla de Contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #6b6b6b;color:#6b6b6b\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #6b6b6b;color:#6b6b6b\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/twind.io\/co\/blog\/prl\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\/#%C2%BFQue_se_entiende_por_SST\" >\u00bfQu\u00e9 se entiende por SST?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/twind.io\/co\/blog\/prl\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\/#%C2%BFCual_es_el_objetivo_de_la_SST\" >\u00bfCu\u00e1l es el objetivo de la SST?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/twind.io\/co\/blog\/prl\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\/#%C2%BFQue_servicios_presta_un_SST\" >\u00bfQu\u00e9 servicios presta un SST?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/twind.io\/co\/blog\/prl\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\/#%C2%BFQuien_se_encarga_de_la_Seguridad_y_Salud_en_el_Trabajo\" >\u00bfQui\u00e9n se encarga de la Seguridad y Salud en el Trabajo?<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFQue_se_entiende_por_SST\"><\/span><strong>\u00bfQu\u00e9 se entiende por SST?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La <strong>SST (Seguridad y Salud en el Trabajo)<\/strong> es un conjunto de normas, actividades y medidas preventivas que buscan proteger la integridad f\u00edsica y mental de los trabajadores, as\u00ed como prevenir y controlar los riesgos laborales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El SST se basa en la <strong>participaci\u00f3n activa de los empleadores, los trabajadores y las autoridades competentes<\/strong>, quienes deben cumplir con sus deberes y responsabilidades en materia de seguridad y salud en el trabajo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La <strong>Seguridad y Salud en el Trabajo<\/strong> se rige por la normatividad vigente, especialmente por el <a href=\"https:\/\/twind.io\/co\/decreto-1072-de-2015-capitulo-6-promoviendo-la-seguridad-laboral-en-colombia\/\">Decreto 1072 de 2015<\/a> y la <a href=\"https:\/\/twind.io\/co\/resolucion-0312-de-2019-estandares-y-aplicacion\/\">Resoluci\u00f3n 0312 de 2019<\/a>, que establecen los est\u00e1ndares m\u00ednimos que deben cumplir las organizaciones para implementar el sistema.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFCual_es_el_objetivo_de_la_SST\"><\/span><strong>\u00bfCu\u00e1l es el objetivo de la SST?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El SST tiene como objetivo prevenir los accidentes laborales y las enfermedades profesionales, as\u00ed como promover el bienestar, la productividad y la competitividad de las empresas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La <strong>Seguridad y Salud en el Trabajo<\/strong> se basa en el principio de que <strong>todo trabajador tiene derecho a desarrollar sus actividades en un entorno seguro y saludable<\/strong>, y que el empleador tiene la responsabilidad de garantizar dicho entorno. La Seguridad y Salud en el Trabajo implica la participaci\u00f3n activa de todos los actores involucrados en el proceso productivo, desde los propios trabajadores hasta las autoridades competentes, pasando por los representantes sindicales, los servicios de prevenci\u00f3n, los proveedores, los clientes y la sociedad en general.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFQue_servicios_presta_un_SST\"><\/span><strong>\u00bfQu\u00e9 servicios presta un SST?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Un SST se encarga de <strong>identificar, evaluar y controlar los riesgos laborales<\/strong>, as\u00ed como de promover una cultura de prevenci\u00f3n y autocuidado entre los empleados y empleadoras. Un SST tambi\u00e9n debe garantizar la atenci\u00f3n m\u00e9dica y la rehabilitaci\u00f3n de las personas que sufran accidentes o enfermedades relacionadas con su trabajo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algunos de los servicios que presta son:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Elaborar y actualizar el perfil sociodemogr\u00e1fico y ocupacional de los trabajadores.<\/li>\n\n\n\n<li>Realizar ex\u00e1menes m\u00e9dicos ocupacionales de ingreso, peri\u00f3dicos y de egreso.<\/li>\n\n\n\n<li>Dise\u00f1ar e implementar programas de vigilancia epidemiol\u00f3gica, promoci\u00f3n y prevenci\u00f3n.<\/li>\n\n\n\n<li>Capacitar y sensibilizar a los trabajadores sobre sus derechos y deberes en materia de seguridad y salud en el trabajo.<\/li>\n\n\n\n<li>Realizar inspecciones, auditor\u00edas y evaluaciones del cumplimiento de las normas de SST.<\/li>\n\n\n\n<li>Investigar y reportar los incidentes, accidentes y enfermedades laborales.<\/li>\n\n\n\n<li>Gestionar la afiliaci\u00f3n y el pago de las cotizaciones al Sistema General de Riesgos Laborales.<\/li>\n\n\n\n<li>Asesorar y acompa\u00f1ar a los trabajadores en el proceso de calificaci\u00f3n, reconocimiento y pago de las prestaciones econ\u00f3micas por incapacidad, invalidez o muerte.<\/li>\n\n\n\n<li>Implementar medidas correctivas y preventivas para mejorar las condiciones de trabajo y reducir los riesgos laborales.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFQuien_se_encarga_de_la_Seguridad_y_Salud_en_el_Trabajo\"><\/span><strong>\u00bfQui\u00e9n se encarga de la <strong>Seguridad y Salud en el Trabajo<\/strong>?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En Colombia, la <strong>Seguridad y Salud en el Trabajo<\/strong> est\u00e1 regulada por el <a href=\"https:\/\/www.mintrabajo.gov.co\/web\/guest\/inicio\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Ministerio del Trabajo de Colombia<\/a>, que es el encargado de establecer las pol\u00edticas, planes y programas para promover una cultura de prevenci\u00f3n y protecci\u00f3n en las empresas. El Ministerio del Trabajo tambi\u00e9n se encarga de <strong>vigilar y sancionar el cumplimiento de la normatividad en materia de SST<\/strong> por parte de los empleadores y los trabajadores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s del Ministerio del Trabajo, existen otras entidades que participan en la gesti\u00f3n de la SST en Colombia, como son:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El <a href=\"https:\/\/www.minsalud.gov.co\/Portada2021\/index.html\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Ministerio de Salud y Protecci\u00f3n Social<\/a>, que define los lineamientos t\u00e9cnicos y cient\u00edficos para la prevenci\u00f3n de enfermedades laborales y la promoci\u00f3n de la salud ocupacional.<\/li>\n\n\n\n<li>La Superintendencia Nacional de Salud, que supervisa el funcionamiento del Sistema General de Riesgos Laborales (SGRL), que es el conjunto de entidades p\u00fablicas y privadas que prestan servicios de salud, pensi\u00f3n, riesgos profesionales y asistencia social a los trabajadores afiliados.<\/li>\n\n\n\n<li>Las Administradoras de Riesgos Laborales (ARL), que son las entidades encargadas de administrar el seguro obligatorio de riesgos laborales, que cubre los accidentes de trabajo y las enfermedades profesionales de los trabajadores afiliados.<\/li>\n\n\n\n<li>Los Comit\u00e9s Paritarios de Seguridad y Salud en el Trabajo (COPASST), que son los \u00f3rganos colegiados conformados por representantes de los empleadores y los trabajadores, que tienen como funci\u00f3n principal asesorar, vigilar y evaluar el SG-SST en cada empresa.<\/li>\n\n\n\n<li>Los Vig\u00edas Ocupacionales, que son los trabajadores designados por el empleador o elegidos por sus compa\u00f1eros, que tienen como funci\u00f3n colaborar con el COPASST en la identificaci\u00f3n y control de los riesgos laborales en su \u00e1rea o proceso.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Para concluir, es importante mencionar que la gesti\u00f3n de la <strong>Seguridad y Salud en el Trabajo<\/strong> puede ser una tarea compleja. Sin embargo, con el software&nbsp;<strong>Twind<\/strong>, este proceso se simplifica enormemente. Twind te proporciona las herramientas necesarias para manejar eficientemente la SST, permiti\u00e9ndote centrarte en lo m\u00e1s importante: garantizar un ambiente laboral seguro y saludable. \u00a1Descubre c\u00f3mo <a href=\"https:\/\/twind.io\/co\/\">Twind<\/a> puede facilitar tu gesti\u00f3n de la SST hoy mismo!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el mundo laboral de Colombia, la&nbsp;SST&nbsp;o&nbsp;Seguridad y Salud en el Trabajo&nbsp;es un t\u00e9rmino de gran importancia. Este art\u00edculo te va a dar el dato completo de lo que significa la SST, su objetivo principal de garantizar un ambiente laboral seguro y saludable, los servicios que presta para lograr este objetivo y qui\u00e9n es el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1626,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":"","tve_updated_post":"","tve_custom_css":"","tve_user_custom_css":"","tve_globals":{},"tcb2_ready":0,"tcb_editor_enabled":0,"tve_landing_page":"","_tve_header":"","_tve_footer":""},"categories":[1],"tags":[],"class_list":["post-1619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prl","post-wrapper","thrv_wrapper"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SST en Colombia: Gu\u00eda sobre Seguridad y Salud en el Trabajo<\/title>\n<meta name=\"description\" content=\"Descubre todo sobre la SST en Colombia. Aprende sobre su objetivo, los servicios que presta y qui\u00e9n se encarga de su supervisi\u00f3n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/twind.io\/co\/blog\/prl\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SST en Colombia: Gu\u00eda sobre Seguridad y Salud en el Trabajo\" \/>\n<meta property=\"og:description\" content=\"Descubre todo sobre la SST en Colombia. Aprende sobre su objetivo, los servicios que presta y qui\u00e9n se encarga de su supervisi\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/twind.io\/co\/blog\/prl\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\/\" \/>\n<meta property=\"og:site_name\" content=\"Twind - Plataforma Gesti\u00f3n Documental de Contratistas\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-30T12:06:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-30T12:06:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/twind.io\/co\/wp-content\/uploads\/2024\/01\/SST.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1688\" \/>\n\t<meta property=\"og:image:height\" content=\"1125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Team Twind\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Team Twind\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/blog\\\/prl\\\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/blog\\\/prl\\\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\\\/\"},\"author\":{\"name\":\"Team Twind\",\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/#\\\/schema\\\/person\\\/cf8157062a3bd3bf249dae644cf59b61\"},\"headline\":\"SST: Entendiendo la Seguridad y Salud en el Trabajo en Colombia\",\"datePublished\":\"2024-01-30T12:06:55+00:00\",\"dateModified\":\"2024-01-30T12:06:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/blog\\\/prl\\\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\\\/\"},\"wordCount\":901,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/blog\\\/prl\\\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/twind.io\\\/co\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/SST.jpg\",\"articleSection\":[\"Seguridad y Salud en el trabajo\"],\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/twind.io\\\/co\\\/blog\\\/prl\\\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/blog\\\/prl\\\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\\\/\",\"url\":\"https:\\\/\\\/twind.io\\\/co\\\/blog\\\/prl\\\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\\\/\",\"name\":\"SST en Colombia: Gu\u00eda sobre Seguridad y Salud en el Trabajo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/blog\\\/prl\\\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/blog\\\/prl\\\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/twind.io\\\/co\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/SST.jpg\",\"datePublished\":\"2024-01-30T12:06:55+00:00\",\"dateModified\":\"2024-01-30T12:06:57+00:00\",\"description\":\"Descubre todo sobre la SST en Colombia. Aprende sobre su objetivo, los servicios que presta y qui\u00e9n se encarga de su supervisi\u00f3n\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/blog\\\/prl\\\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/twind.io\\\/co\\\/blog\\\/prl\\\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/blog\\\/prl\\\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/twind.io\\\/co\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/SST.jpg\",\"contentUrl\":\"https:\\\/\\\/twind.io\\\/co\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/SST.jpg\",\"width\":1688,\"height\":1125,\"caption\":\"Seguridad y Salud en el Trabajo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/blog\\\/prl\\\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/twind.io\\\/co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SST: Entendiendo la Seguridad y Salud en el Trabajo en Colombia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/#website\",\"url\":\"https:\\\/\\\/twind.io\\\/co\\\/\",\"name\":\"Twind - Plataforma Gesti\u00f3n Documental de Contratistas\",\"description\":\"Plataforma para la Gesti\u00f3n Documental de Contratistas para asegurar los est\u00e1ndares de Seguridad y Salud en el Trabajo\",\"publisher\":{\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/twind.io\\\/co\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/#organization\",\"name\":\"Twind - Plataforma Gesti\u00f3n Documental de Contratistas\",\"url\":\"https:\\\/\\\/twind.io\\\/co\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/twind.io\\\/co\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logo-Twind.svg\",\"contentUrl\":\"https:\\\/\\\/twind.io\\\/co\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logo-Twind.svg\",\"width\":1,\"height\":1,\"caption\":\"Twind - Plataforma Gesti\u00f3n Documental de Contratistas\"},\"image\":{\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/#\\\/schema\\\/person\\\/cf8157062a3bd3bf249dae644cf59b61\",\"name\":\"Team Twind\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g\",\"caption\":\"Team Twind\"},\"description\":\"Comunicaci\u00f3n y contenidos\",\"sameAs\":[\"https:\\\/\\\/twind.io\\\/co\\\/\"],\"url\":\"https:\\\/\\\/twind.io\\\/co\\\/blog\\\/author\\\/rrios_6eq9khcx\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SST en Colombia: Gu\u00eda sobre Seguridad y Salud en el Trabajo","description":"Descubre todo sobre la SST en Colombia. Aprende sobre su objetivo, los servicios que presta y qui\u00e9n se encarga de su supervisi\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/twind.io\/co\/blog\/prl\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\/","og_locale":"es_ES","og_type":"article","og_title":"SST en Colombia: Gu\u00eda sobre Seguridad y Salud en el Trabajo","og_description":"Descubre todo sobre la SST en Colombia. Aprende sobre su objetivo, los servicios que presta y qui\u00e9n se encarga de su supervisi\u00f3n","og_url":"https:\/\/twind.io\/co\/blog\/prl\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\/","og_site_name":"Twind - Plataforma Gesti\u00f3n Documental de Contratistas","article_published_time":"2024-01-30T12:06:55+00:00","article_modified_time":"2024-01-30T12:06:57+00:00","og_image":[{"width":1688,"height":1125,"url":"https:\/\/twind.io\/co\/wp-content\/uploads\/2024\/01\/SST.jpg","type":"image\/jpeg"}],"author":"Team Twind","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Team Twind","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/twind.io\/co\/blog\/prl\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\/#article","isPartOf":{"@id":"https:\/\/twind.io\/co\/blog\/prl\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\/"},"author":{"name":"Team Twind","@id":"https:\/\/twind.io\/co\/#\/schema\/person\/cf8157062a3bd3bf249dae644cf59b61"},"headline":"SST: Entendiendo la Seguridad y Salud en el Trabajo en Colombia","datePublished":"2024-01-30T12:06:55+00:00","dateModified":"2024-01-30T12:06:57+00:00","mainEntityOfPage":{"@id":"https:\/\/twind.io\/co\/blog\/prl\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\/"},"wordCount":901,"commentCount":0,"publisher":{"@id":"https:\/\/twind.io\/co\/#organization"},"image":{"@id":"https:\/\/twind.io\/co\/blog\/prl\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\/#primaryimage"},"thumbnailUrl":"https:\/\/twind.io\/co\/wp-content\/uploads\/2024\/01\/SST.jpg","articleSection":["Seguridad y Salud en el trabajo"],"inLanguage":"es-CO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/twind.io\/co\/blog\/prl\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/twind.io\/co\/blog\/prl\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\/","url":"https:\/\/twind.io\/co\/blog\/prl\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\/","name":"SST en Colombia: Gu\u00eda sobre Seguridad y Salud en el Trabajo","isPartOf":{"@id":"https:\/\/twind.io\/co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/twind.io\/co\/blog\/prl\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\/#primaryimage"},"image":{"@id":"https:\/\/twind.io\/co\/blog\/prl\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\/#primaryimage"},"thumbnailUrl":"https:\/\/twind.io\/co\/wp-content\/uploads\/2024\/01\/SST.jpg","datePublished":"2024-01-30T12:06:55+00:00","dateModified":"2024-01-30T12:06:57+00:00","description":"Descubre todo sobre la SST en Colombia. Aprende sobre su objetivo, los servicios que presta y qui\u00e9n se encarga de su supervisi\u00f3n","breadcrumb":{"@id":"https:\/\/twind.io\/co\/blog\/prl\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/twind.io\/co\/blog\/prl\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/twind.io\/co\/blog\/prl\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\/#primaryimage","url":"https:\/\/twind.io\/co\/wp-content\/uploads\/2024\/01\/SST.jpg","contentUrl":"https:\/\/twind.io\/co\/wp-content\/uploads\/2024\/01\/SST.jpg","width":1688,"height":1125,"caption":"Seguridad y Salud en el Trabajo"},{"@type":"BreadcrumbList","@id":"https:\/\/twind.io\/co\/blog\/prl\/sst-en-colombia-guia-completa-sobre-seguridad-y-salud-en-el-trabajo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/twind.io\/co\/"},{"@type":"ListItem","position":2,"name":"SST: Entendiendo la Seguridad y Salud en el Trabajo en Colombia"}]},{"@type":"WebSite","@id":"https:\/\/twind.io\/co\/#website","url":"https:\/\/twind.io\/co\/","name":"Twind - Plataforma Gesti\u00f3n Documental de Contratistas","description":"Plataforma para la Gesti\u00f3n Documental de Contratistas para asegurar los est\u00e1ndares de Seguridad y Salud en el Trabajo","publisher":{"@id":"https:\/\/twind.io\/co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/twind.io\/co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/twind.io\/co\/#organization","name":"Twind - Plataforma Gesti\u00f3n Documental de Contratistas","url":"https:\/\/twind.io\/co\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/twind.io\/co\/#\/schema\/logo\/image\/","url":"https:\/\/twind.io\/co\/wp-content\/uploads\/2023\/04\/Logo-Twind.svg","contentUrl":"https:\/\/twind.io\/co\/wp-content\/uploads\/2023\/04\/Logo-Twind.svg","width":1,"height":1,"caption":"Twind - Plataforma Gesti\u00f3n Documental de Contratistas"},"image":{"@id":"https:\/\/twind.io\/co\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/twind.io\/co\/#\/schema\/person\/cf8157062a3bd3bf249dae644cf59b61","name":"Team Twind","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g","caption":"Team Twind"},"description":"Comunicaci\u00f3n y contenidos","sameAs":["https:\/\/twind.io\/co\/"],"url":"https:\/\/twind.io\/co\/blog\/author\/rrios_6eq9khcx\/"}]}},"_links":{"self":[{"href":"https:\/\/twind.io\/co\/wp-json\/wp\/v2\/posts\/1619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/twind.io\/co\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/twind.io\/co\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/twind.io\/co\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/twind.io\/co\/wp-json\/wp\/v2\/comments?post=1619"}],"version-history":[{"count":8,"href":"https:\/\/twind.io\/co\/wp-json\/wp\/v2\/posts\/1619\/revisions"}],"predecessor-version":[{"id":1628,"href":"https:\/\/twind.io\/co\/wp-json\/wp\/v2\/posts\/1619\/revisions\/1628"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/twind.io\/co\/wp-json\/wp\/v2\/media\/1626"}],"wp:attachment":[{"href":"https:\/\/twind.io\/co\/wp-json\/wp\/v2\/media?parent=1619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/twind.io\/co\/wp-json\/wp\/v2\/categories?post=1619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/twind.io\/co\/wp-json\/wp\/v2\/tags?post=1619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}