{"id":2373,"date":"2024-10-31T12:24:33","date_gmt":"2024-10-31T12:24:33","guid":{"rendered":"https:\/\/twind.io\/co\/?p=2373"},"modified":"2024-10-31T12:28:00","modified_gmt":"2024-10-31T12:28:00","slug":"normatividad-en-seguridad-y-salud-en-el-trabajo","status":"publish","type":"post","link":"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/","title":{"rendered":"Normatividad en Seguridad y Salud en el Trabajo: Gu\u00eda Completa para el 2024"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La <strong>Seguridad y Salud en el Trabajo (SST)<\/strong> es fundamental para proteger a los empleados y cumplir con los requisitos legales en Colombia. Este art\u00edculo aborda las normativas vigentes en SST, ayudando a los responsables de HSE a implementar y mantener un Sistema de Gesti\u00f3n en Seguridad y Salud en el Trabajo (SG-SST) que se ajuste a la legislaci\u00f3n actual, brindando tanto seguridad como competitividad.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Tabla de Contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #6b6b6b;color:#6b6b6b\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #6b6b6b;color:#6b6b6b\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/#%C2%BFQue_es_la_Normatividad_en_SST\" >\u00bfQu\u00e9 es la Normatividad en SST?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/#Importancia_del_Cumplimiento_en_SST\" >Importancia del Cumplimiento en SST<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/#Principales_Normas_en_SST_en_Colombia\" >Principales Normas en SST en Colombia<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/#Ley_9_de_1979\" >Ley 9 de 1979<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/#Decreto_1072_de_2015\" >Decreto 1072 de 2015<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/#Ley_1562_de_2012\" >Ley 1562 de 2012<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/#Requisitos_Especificos_para_Actividades_de_Alto_Riesgo\" >Requisitos Espec\u00edficos para Actividades de Alto Riesgo<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/#Resolucion_4272_de_2021\" >Resoluci\u00f3n 4272 de 2021<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/#Resolucion_4919_de_2018\" >Resoluci\u00f3n 4919 de 2018<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/#Ley_55_de_1993\" >Ley 55 de 1993<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/#Evaluacion_de_Factores_de_Riesgo_Psicosocial\" >Evaluaci\u00f3n de Factores de Riesgo Psicosocial<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/#Resolucion_2646_de_2008\" >Resoluci\u00f3n 2646 de 2008<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/#Resolucion_2764_de_2022\" >Resoluci\u00f3n 2764 de 2022<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/#Creacion_y_Actualizacion_de_la_Matriz_Legal_en_SST\" >Creaci\u00f3n y Actualizaci\u00f3n de la Matriz Legal en SST<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/#Implementacion_y_Monitoreo_del_SG-SST\" >Implementaci\u00f3n y Monitoreo del SG-SST<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/#Indicadores_de_Desempeno_en_SST\" >Indicadores de Desempe\u00f1o en SST<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/#Supervision_de_las_Condiciones_de_SST\" >Supervisi\u00f3n de las Condiciones de SST<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/#Conclusion\" >Conclusi\u00f3n<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFQue_es_la_Normatividad_en_SST\"><\/span><strong>\u00bfQu\u00e9 es la Normatividad en SST?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La <strong>normatividad en Seguridad y Salud en el Trabajo<\/strong> incluye todas las leyes, decretos y resoluciones que establecen los lineamientos y est\u00e1ndares m\u00ednimos que deben cumplir las empresas en Colombia para garantizar un ambiente de trabajo seguro y saludable. Esta normativa se actualiza con frecuencia para incorporar nuevas medidas de seguridad y abordar riesgos emergentes, como los derivados de la COVID-19.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Importancia_del_Cumplimiento_en_SST\"><\/span><strong>Importancia del Cumplimiento en SST<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Cumplir con la <strong>normatividad en SST<\/strong> ayuda a las empresas a evitar sanciones legales, mejorar la moral de los empleados, y reducir accidentes y enfermedades laborales. Adem\u00e1s, una buena gesti\u00f3n en SST puede elevar la productividad y optimizar los recursos, generando un ambiente laboral seguro que impacta positivamente en la competitividad empresarial\u200b.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Principales_Normas_en_SST_en_Colombia\"><\/span><strong>Principales Normas en SST en Colombia<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Ley_9_de_1979\"><\/span><strong>Ley 9 de 1979<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Considerada una de las primeras leyes en establecer el marco legal de SST en Colombia, la Ley 9 de 1979 obliga a los empleadores a adoptar medidas de seguridad y salud en el lugar de trabajo, incluyendo la implementaci\u00f3n de sistemas de control para prevenir enfermedades y accidentes\u200b<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Decreto_1072_de_2015\"><\/span><strong>Decreto 1072 de 2015<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Este decreto es el pilar del SG-SST en Colombia, obligatorio para todas las empresas y adaptable seg\u00fan la actividad econ\u00f3mica y nivel de riesgo. El <a href=\"https:\/\/twind.io\/co\/todo-lo-que-debes-saber-sobre-el-decreto-1072-de-2015\/\">Decreto 1072<\/a> establece los requerimientos de implementaci\u00f3n y seguimiento del SG-SST, adem\u00e1s de establecer los roles y responsabilidades de empleadores y empleados para garantizar su eficacia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Ley_1562_de_2012\"><\/span><strong>Ley 1562 de 2012<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La <a href=\"https:\/\/twind.io\/co\/ley-1562-de-2012-analisis-detallado-de-su-impacto-y-significado\/\">Ley 1562<\/a> es una reforma del Sistema General de Riesgos Laborales que moderniza conceptos claves en SST y ampl\u00eda las obligaciones en gesti\u00f3n de riesgos, orientada a proteger la salud de los trabajadores a trav\u00e9s de pol\u00edticas preventivas. Esta ley define la administraci\u00f3n de riesgos laborales como responsabilidad de las Administradoras de Riesgos Laborales (ARL), bajo la supervisi\u00f3n del Ministerio de Trabajo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Requisitos_Especificos_para_Actividades_de_Alto_Riesgo\"><\/span><strong>Requisitos Espec\u00edficos para Actividades de Alto Riesgo<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Resolucion_4272_de_2021\"><\/span><strong>Resoluci\u00f3n 4272 de 2021<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Reglamenta el trabajo en alturas y exige que los empleadores capaciten a los trabajadores en medidas de protecci\u00f3n y monitoreen constantemente las condiciones de seguridad en estas tareas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Resolucion_4919_de_2018\"><\/span><strong>Resoluci\u00f3n 4919 de 2018<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Aplica a tareas en espacios confinados, imponiendo medidas espec\u00edficas de ventilaci\u00f3n y equipos de protecci\u00f3n personal. Estas tareas requieren protocolos adicionales de emergencia y un sistema de permisos supervisado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Ley_55_de_1993\"><\/span><strong>Ley 55 de 1993<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Normativa para el manejo seguro de sustancias qu\u00edmicas, obligando a las empresas a implementar medidas de protecci\u00f3n, capacitaci\u00f3n y control para prevenir intoxicaciones y otras enfermedades laborales relacionada.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Evaluacion_de_Factores_de_Riesgo_Psicosocial\"><\/span><strong>Evaluaci\u00f3n de Factores de Riesgo Psicosocial<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Resolucion_2646_de_2008\"><\/span><strong>Resoluci\u00f3n 2646 de 2008<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Exige que las empresas eval\u00faen y gestionen los factores de riesgo psicosocial, especialmente en entornos laborales de alto estr\u00e9s, para prevenir enfermedades relacionadas con el bienestar mental\u200b.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Resolucion_2764_de_2022\"><\/span><strong>Resoluci\u00f3n 2764 de 2022<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Actualiza las directrices para evaluar el riesgo psicosocial y establece la periodicidad de las evaluaciones seg\u00fan el nivel de riesgo. Los empleadores deben documentar, implementar y controlar los resultados para garantizar el bienestar mental de los empleados.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Creacion_y_Actualizacion_de_la_Matriz_Legal_en_SST\"><\/span><strong>Creaci\u00f3n y Actualizaci\u00f3n de la Matriz Legal en SST<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La <a href=\"https:\/\/ctaima.co\/como-realizar-una-matriz-de-requisitos-legales-para-tu-sistema-de-gestion-de-seguridad-y-salud-en-el-trabajo\/\">matriz legal<\/a> es una herramienta fundamental para cumplir con la normativa en SST. Incluye todas las leyes y normativas aplicables en funci\u00f3n de la actividad econ\u00f3mica y riesgos de cada empresa. Los responsables del SG-SST deben actualizarla con cada nueva resoluci\u00f3n o decreto emitido por el Ministerio de Trabajo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Implementacion_y_Monitoreo_del_SG-SST\"><\/span><strong>Implementaci\u00f3n y Monitoreo del SG-SST<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Indicadores_de_Desempeno_en_SST\"><\/span><strong>Indicadores de Desempe\u00f1o en SST<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La implementaci\u00f3n de un SG-SST efectivo incluye el uso de indicadores de estructura (recursos disponibles), proceso (grado de desarrollo) y resultado (cambios logrados). Estos indicadores permiten evaluar la efectividad del SG-SST y garantizan la mejora continua.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Supervision_de_las_Condiciones_de_SST\"><\/span><strong>Supervisi\u00f3n de las Condiciones de SST<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El Ministerio de Trabajo exige que las empresas mantengan registros actualizados de SST, identificando riesgos, evaluando condiciones y realizando auditor\u00edas para asegurar el cumplimiento y la protecci\u00f3n de los trabajadores.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Conclusion\"><\/span><strong>Conclusi\u00f3n<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La normatividad en Seguridad y Salud en el Trabajo en Colombia es un marco legal amplio y en constante cambio. Para cumplirla adecuadamente, es fundamental que las empresas realicen una revisi\u00f3n peri\u00f3dica y adapten su SG-SST a los nuevos lineamientos y riesgos emergentes. El compromiso de la alta direcci\u00f3n es clave para una implementaci\u00f3n exitosa, y una gesti\u00f3n proactiva de SST mejora tanto la seguridad como la productividad en el entorno laboral.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Seguridad y Salud en el Trabajo (SST) es fundamental para proteger a los empleados y cumplir con los requisitos legales en Colombia. Este art\u00edculo aborda las normativas vigentes en SST, ayudando a los responsables de HSE a implementar y mantener un Sistema de Gesti\u00f3n en Seguridad y Salud en el Trabajo (SG-SST) que se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2377,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":"","tve_updated_post":"","tve_custom_css":"","tve_user_custom_css":"","tve_globals":{},"tcb2_ready":0,"tcb_editor_enabled":0,"tve_landing_page":"","_tve_header":"","_tve_footer":""},"categories":[1],"tags":[],"class_list":["post-2373","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prl","post-wrapper","thrv_wrapper"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Normatividad en Seguridad y Salud en el Trabajo - Twind<\/title>\n<meta name=\"description\" content=\"La normatividad en Seguridad y Salud en el Trabajo incluye todas las leyes, decretos y resoluciones que establecen los est\u00e1ndares m\u00ednimos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Normatividad en Seguridad y Salud en el Trabajo - Twind\" \/>\n<meta property=\"og:description\" content=\"La normatividad en Seguridad y Salud en el Trabajo incluye todas las leyes, decretos y resoluciones que establecen los est\u00e1ndares m\u00ednimos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/\" \/>\n<meta property=\"og:site_name\" content=\"Twind - Plataforma Gesti\u00f3n Documental de Contratistas\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-31T12:24:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-31T12:28:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/twind.io\/co\/wp-content\/uploads\/2024\/10\/normatividad-seguridad-y-salud-en-el-trabajo.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Team Twind\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Team Twind\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/blog\\\/prl\\\/normatividad-en-seguridad-y-salud-en-el-trabajo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/blog\\\/prl\\\/normatividad-en-seguridad-y-salud-en-el-trabajo\\\/\"},\"author\":{\"name\":\"Team Twind\",\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/#\\\/schema\\\/person\\\/cf8157062a3bd3bf249dae644cf59b61\"},\"headline\":\"Normatividad en Seguridad y Salud en el Trabajo: Gu\u00eda Completa para el 2024\",\"datePublished\":\"2024-10-31T12:24:33+00:00\",\"dateModified\":\"2024-10-31T12:28:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/blog\\\/prl\\\/normatividad-en-seguridad-y-salud-en-el-trabajo\\\/\"},\"wordCount\":809,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/blog\\\/prl\\\/normatividad-en-seguridad-y-salud-en-el-trabajo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/twind.io\\\/co\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/normatividad-seguridad-y-salud-en-el-trabajo.webp\",\"articleSection\":[\"Seguridad y Salud en el trabajo\"],\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/twind.io\\\/co\\\/blog\\\/prl\\\/normatividad-en-seguridad-y-salud-en-el-trabajo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/blog\\\/prl\\\/normatividad-en-seguridad-y-salud-en-el-trabajo\\\/\",\"url\":\"https:\\\/\\\/twind.io\\\/co\\\/blog\\\/prl\\\/normatividad-en-seguridad-y-salud-en-el-trabajo\\\/\",\"name\":\"Normatividad en Seguridad y Salud en el Trabajo - Twind\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/blog\\\/prl\\\/normatividad-en-seguridad-y-salud-en-el-trabajo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/blog\\\/prl\\\/normatividad-en-seguridad-y-salud-en-el-trabajo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/twind.io\\\/co\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/normatividad-seguridad-y-salud-en-el-trabajo.webp\",\"datePublished\":\"2024-10-31T12:24:33+00:00\",\"dateModified\":\"2024-10-31T12:28:00+00:00\",\"description\":\"La normatividad en Seguridad y Salud en el Trabajo incluye todas las leyes, decretos y resoluciones que establecen los est\u00e1ndares m\u00ednimos\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/blog\\\/prl\\\/normatividad-en-seguridad-y-salud-en-el-trabajo\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/twind.io\\\/co\\\/blog\\\/prl\\\/normatividad-en-seguridad-y-salud-en-el-trabajo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/blog\\\/prl\\\/normatividad-en-seguridad-y-salud-en-el-trabajo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/twind.io\\\/co\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/normatividad-seguridad-y-salud-en-el-trabajo.webp\",\"contentUrl\":\"https:\\\/\\\/twind.io\\\/co\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/normatividad-seguridad-y-salud-en-el-trabajo.webp\",\"width\":1200,\"height\":800,\"caption\":\"normatividad seguridad y salud en el trabajo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/blog\\\/prl\\\/normatividad-en-seguridad-y-salud-en-el-trabajo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/twind.io\\\/co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Normatividad en Seguridad y Salud en el Trabajo: Gu\u00eda Completa para el 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/#website\",\"url\":\"https:\\\/\\\/twind.io\\\/co\\\/\",\"name\":\"Twind - Plataforma Gesti\u00f3n Documental de Contratistas\",\"description\":\"Plataforma para la Gesti\u00f3n Documental de Contratistas para asegurar los est\u00e1ndares de Seguridad y Salud en el Trabajo\",\"publisher\":{\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/twind.io\\\/co\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/#organization\",\"name\":\"Twind - Plataforma Gesti\u00f3n Documental de Contratistas\",\"url\":\"https:\\\/\\\/twind.io\\\/co\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/twind.io\\\/co\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logo-Twind.svg\",\"contentUrl\":\"https:\\\/\\\/twind.io\\\/co\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logo-Twind.svg\",\"width\":1,\"height\":1,\"caption\":\"Twind - Plataforma Gesti\u00f3n Documental de Contratistas\"},\"image\":{\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/twind.io\\\/co\\\/#\\\/schema\\\/person\\\/cf8157062a3bd3bf249dae644cf59b61\",\"name\":\"Team Twind\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g\",\"caption\":\"Team Twind\"},\"description\":\"Comunicaci\u00f3n y contenidos\",\"sameAs\":[\"https:\\\/\\\/twind.io\\\/co\\\/\"],\"url\":\"https:\\\/\\\/twind.io\\\/co\\\/blog\\\/author\\\/rrios_6eq9khcx\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Normatividad en Seguridad y Salud en el Trabajo - Twind","description":"La normatividad en Seguridad y Salud en el Trabajo incluye todas las leyes, decretos y resoluciones que establecen los est\u00e1ndares m\u00ednimos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/","og_locale":"es_ES","og_type":"article","og_title":"Normatividad en Seguridad y Salud en el Trabajo - Twind","og_description":"La normatividad en Seguridad y Salud en el Trabajo incluye todas las leyes, decretos y resoluciones que establecen los est\u00e1ndares m\u00ednimos","og_url":"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/","og_site_name":"Twind - Plataforma Gesti\u00f3n Documental de Contratistas","article_published_time":"2024-10-31T12:24:33+00:00","article_modified_time":"2024-10-31T12:28:00+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/twind.io\/co\/wp-content\/uploads\/2024\/10\/normatividad-seguridad-y-salud-en-el-trabajo.webp","type":"image\/webp"}],"author":"Team Twind","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Team Twind","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/#article","isPartOf":{"@id":"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/"},"author":{"name":"Team Twind","@id":"https:\/\/twind.io\/co\/#\/schema\/person\/cf8157062a3bd3bf249dae644cf59b61"},"headline":"Normatividad en Seguridad y Salud en el Trabajo: Gu\u00eda Completa para el 2024","datePublished":"2024-10-31T12:24:33+00:00","dateModified":"2024-10-31T12:28:00+00:00","mainEntityOfPage":{"@id":"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/"},"wordCount":809,"commentCount":0,"publisher":{"@id":"https:\/\/twind.io\/co\/#organization"},"image":{"@id":"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/#primaryimage"},"thumbnailUrl":"https:\/\/twind.io\/co\/wp-content\/uploads\/2024\/10\/normatividad-seguridad-y-salud-en-el-trabajo.webp","articleSection":["Seguridad y Salud en el trabajo"],"inLanguage":"es-CO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/","url":"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/","name":"Normatividad en Seguridad y Salud en el Trabajo - Twind","isPartOf":{"@id":"https:\/\/twind.io\/co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/#primaryimage"},"image":{"@id":"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/#primaryimage"},"thumbnailUrl":"https:\/\/twind.io\/co\/wp-content\/uploads\/2024\/10\/normatividad-seguridad-y-salud-en-el-trabajo.webp","datePublished":"2024-10-31T12:24:33+00:00","dateModified":"2024-10-31T12:28:00+00:00","description":"La normatividad en Seguridad y Salud en el Trabajo incluye todas las leyes, decretos y resoluciones que establecen los est\u00e1ndares m\u00ednimos","breadcrumb":{"@id":"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/#primaryimage","url":"https:\/\/twind.io\/co\/wp-content\/uploads\/2024\/10\/normatividad-seguridad-y-salud-en-el-trabajo.webp","contentUrl":"https:\/\/twind.io\/co\/wp-content\/uploads\/2024\/10\/normatividad-seguridad-y-salud-en-el-trabajo.webp","width":1200,"height":800,"caption":"normatividad seguridad y salud en el trabajo"},{"@type":"BreadcrumbList","@id":"https:\/\/twind.io\/co\/blog\/prl\/normatividad-en-seguridad-y-salud-en-el-trabajo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/twind.io\/co\/"},{"@type":"ListItem","position":2,"name":"Normatividad en Seguridad y Salud en el Trabajo: Gu\u00eda Completa para el 2024"}]},{"@type":"WebSite","@id":"https:\/\/twind.io\/co\/#website","url":"https:\/\/twind.io\/co\/","name":"Twind - Plataforma Gesti\u00f3n Documental de Contratistas","description":"Plataforma para la Gesti\u00f3n Documental de Contratistas para asegurar los est\u00e1ndares de Seguridad y Salud en el Trabajo","publisher":{"@id":"https:\/\/twind.io\/co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/twind.io\/co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/twind.io\/co\/#organization","name":"Twind - Plataforma Gesti\u00f3n Documental de Contratistas","url":"https:\/\/twind.io\/co\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/twind.io\/co\/#\/schema\/logo\/image\/","url":"https:\/\/twind.io\/co\/wp-content\/uploads\/2023\/04\/Logo-Twind.svg","contentUrl":"https:\/\/twind.io\/co\/wp-content\/uploads\/2023\/04\/Logo-Twind.svg","width":1,"height":1,"caption":"Twind - Plataforma Gesti\u00f3n Documental de Contratistas"},"image":{"@id":"https:\/\/twind.io\/co\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/twind.io\/co\/#\/schema\/person\/cf8157062a3bd3bf249dae644cf59b61","name":"Team Twind","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g","caption":"Team Twind"},"description":"Comunicaci\u00f3n y contenidos","sameAs":["https:\/\/twind.io\/co\/"],"url":"https:\/\/twind.io\/co\/blog\/author\/rrios_6eq9khcx\/"}]}},"_links":{"self":[{"href":"https:\/\/twind.io\/co\/wp-json\/wp\/v2\/posts\/2373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/twind.io\/co\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/twind.io\/co\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/twind.io\/co\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/twind.io\/co\/wp-json\/wp\/v2\/comments?post=2373"}],"version-history":[{"count":5,"href":"https:\/\/twind.io\/co\/wp-json\/wp\/v2\/posts\/2373\/revisions"}],"predecessor-version":[{"id":2379,"href":"https:\/\/twind.io\/co\/wp-json\/wp\/v2\/posts\/2373\/revisions\/2379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/twind.io\/co\/wp-json\/wp\/v2\/media\/2377"}],"wp:attachment":[{"href":"https:\/\/twind.io\/co\/wp-json\/wp\/v2\/media?parent=2373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/twind.io\/co\/wp-json\/wp\/v2\/categories?post=2373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/twind.io\/co\/wp-json\/wp\/v2\/tags?post=2373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}