{"id":35493,"date":"2025-02-27T08:02:13","date_gmt":"2025-02-27T08:02:13","guid":{"rendered":"https:\/\/www.ctaima.com\/?p=35493"},"modified":"2026-06-29T10:37:34","modified_gmt":"2026-06-29T10:37:34","slug":"trabajos-en-altura-normativa-prevencion-rd-2177","status":"publish","type":"post","link":"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/","title":{"rendered":"Trabajos en Altura: Normativa, Riesgos y Prevenci\u00f3n"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Los <strong>trabajos en altura<\/strong> representan una de las actividades laborales con <strong>mayor \u00edndice de siniestralidad<\/strong> en Espa\u00f1a. A pesar de los avances normativos y t\u00e9cnicos de los \u00faltimos a\u00f1os, siguen siendo causa de accidentes graves y mortales en diversos sectores profesionales. Esta gu\u00eda completa aborda todos los aspectos fundamentales que debes conocer sobre los trabajos en altura, desde su definici\u00f3n legal hasta las medidas preventivas m\u00e1s efectivas.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Tabla de contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #6b6b6b;color:#6b6b6b\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #6b6b6b;color:#6b6b6b\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/#%C2%BFCuando_se_considera_trabajo_en_altura\" >\u00bfCu\u00e1ndo se considera trabajo en altura?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/#Normativa_sobre_trabajos_en_altura\" >Normativa sobre trabajos en altura<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/#%C2%BFCuales_son_los_tipos_de_trabajos_en_altura\" >\u00bfCu\u00e1les son los tipos de trabajos en altura?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/#%C2%BFCuales_son_los_4_riesgos_principales_en_un_trabajo_en_altura\" >\u00bfCu\u00e1les son los 4 riesgos principales en un trabajo en altura?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/#%C2%BFCuales_son_las_normas_para_trabajar_en_altura\" >\u00bfCu\u00e1les son las normas para trabajar en altura?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/#Medidas_preventivas_para_trabajos_en_altura\" >Medidas preventivas para trabajos en altura<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/#Equipos_de_proteccion_individual_para_trabajos_en_altura\" >Equipos de protecci\u00f3n individual para trabajos en altura<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/#Formacion_necesaria_para_trabajos_en_altura\" >Formaci\u00f3n necesaria para trabajos en altura<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/#Preguntas_frecuentes_sobre_trabajos_en_altura\" >Preguntas frecuentes sobre trabajos en altura<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/#Conclusiones_claves_para_la_seguridad_en_trabajos_en_altura\" >Conclusiones: claves para la seguridad en trabajos en altura<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFCuando_se_considera_trabajo_en_altura\"><\/span><strong>\u00bfCu\u00e1ndo se considera trabajo en altura?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan la normativa vigente en Espa\u00f1a, <strong>se considera trabajo en altura cualquier actividad que se realice a partir de 2 metros de altura respecto al nivel del suelo<\/strong>. Esta distancia se mide desde la superficie en la que est\u00e1 situado el trabajador hasta el nivel inferior en el que quedar\u00eda retenido en caso de ca\u00edda. Tambi\u00e9n se incluyen actividades realizadas a m\u00e1s de 3,5 metros de altura desde el punto de operaci\u00f3n al suelo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es importante destacar que esta definici\u00f3n, aunque no est\u00e1 expl\u00edcitamente detallada en la legislaci\u00f3n, es ampliamente aceptada en el \u00e1mbito de la prevenci\u00f3n de riesgos laborales y sirve como referencia para aplicar las medidas de seguridad correspondientes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Normativa_sobre_trabajos_en_altura\"><\/span><strong>Normativa sobre trabajos en altura<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La legislaci\u00f3n espa\u00f1ola regula los trabajos en altura a trav\u00e9s de diversas normativas que establecen las condiciones m\u00ednimas de seguridad y salud. Las principales referencias legales son:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/twind.io\/es\/ley-31-1995-prevencion-riesgos-laborales\/\">Ley 31\/1995, de 8 de noviembre<\/a><\/strong>, de Prevenci\u00f3n de Riesgos Laborales, que establece el marco general para garantizar la seguridad y salud de los trabajadores.<\/li>\n\n\n\n<li><strong><a href=\"https:\/\/www.boe.es\/buscar\/doc.php?id=BOE-A-2004-19311\" type=\"link\" id=\"https:\/\/www.boe.es\/buscar\/doc.php?id=BOE-A-2004-19311\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Real Decreto 2177\/2004<\/a><\/strong>, que modifica el RD 1215\/1997, estableciendo disposiciones m\u00ednimas de seguridad y salud para la utilizaci\u00f3n por los trabajadores de equipos de trabajo en materia de trabajos temporales en altura.<\/li>\n\n\n\n<li><strong><a href=\"https:\/\/twind.io\/es\/rd-1627-97-seguridad-obras-construccion\/\">Real Decreto 1627\/1997<\/a><\/strong>, sobre disposiciones m\u00ednimas de seguridad y salud en obras de construcci\u00f3n.<\/li>\n\n\n\n<li><strong><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-1997-8669\" type=\"link\" id=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-1997-8669\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Real Decreto 486\/1997<\/a><\/strong>, por el que se establecen las disposiciones m\u00ednimas de seguridad y salud en los lugares de trabajo.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Estas normativas obligan al empresario a <strong>garantizar la seguridad de todos los trabajadores<\/strong> que realizan tareas en altura, mediante evaluaciones de riesgos, formaci\u00f3n adecuada y dotaci\u00f3n de equipos de protecci\u00f3n necesarios.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFCuales_son_los_tipos_de_trabajos_en_altura\"><\/span><strong>\u00bfCu\u00e1les son los tipos de trabajos en altura?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los trabajos en altura comprenden diversas actividades en diferentes sectores. Los principales tipos son:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Trabajos en andamios y plataformas elevadoras<\/strong>: Utilizados principalmente en construcci\u00f3n, mantenimiento de fachadas y tareas de rehabilitaci\u00f3n.<\/li>\n\n\n\n<li><strong>Trabajos en postes, torres y antenas<\/strong>: Comunes en telecomunicaciones, electricidad y montaje de estructuras.<\/li>\n\n\n\n<li><strong>Trabajos en tejados y cubiertas<\/strong>: Habituales en construcci\u00f3n, mantenimiento de edificios e instalaci\u00f3n de equipos.<\/li>\n\n\n\n<li><strong>Trabajos verticales o de acceso mediante cuerdas<\/strong>: Empleados en limpieza de fachadas, mantenimiento de estructuras de dif\u00edcil acceso y trabajos en espacios confinados con acceso en altura.<\/li>\n\n\n\n<li><strong>Trabajos en escaleras manuales<\/strong>: Presentes en pr\u00e1cticamente todos los sectores para tareas de corta duraci\u00f3n y altura limitada.<\/li>\n\n\n\n<li><strong>Trabajos de montaje y desmontaje de estructuras temporales<\/strong>: Como escenarios, carpas o instalaciones para eventos.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Cada tipo de trabajo en altura presenta <strong>caracter\u00edsticas y riesgos espec\u00edficos<\/strong> que requieren medidas preventivas adaptadas a sus particularidades.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFCuales_son_los_4_riesgos_principales_en_un_trabajo_en_altura\"><\/span><strong>\u00bfCu\u00e1les son los 4 riesgos principales en un trabajo en altura?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque los trabajos en altura implican m\u00faltiples riesgos, podemos destacar cuatro como los m\u00e1s significativos:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Ca\u00eddas a distinto nivel<\/strong>: Constituyen el riesgo principal y m\u00e1s grave, pudiendo provocar lesiones severas o mortales. Estas ca\u00eddas pueden producirse por falta de protecciones colectivas, uso inadecuado de EPIs, p\u00e9rdida de equilibrio o rotura de superficies de apoyo.<\/li>\n\n\n\n<li><strong>Ca\u00edda de objetos sobre personas<\/strong>: Las herramientas, materiales o equipos que caen desde altura pueden causar graves lesiones a trabajadores o personas que se encuentren en niveles inferiores.<\/li>\n\n\n\n<li><strong>Contactos el\u00e9ctricos<\/strong>: En trabajos cerca de l\u00edneas el\u00e9ctricas o instalaciones energizadas, el riesgo de electrocuci\u00f3n es elevado y puede desencadenar ca\u00eddas u otros accidentes secundarios.<\/li>\n\n\n\n<li><strong>Riesgos posturales y ergon\u00f3micos<\/strong>: Las posturas forzadas, los sobreesfuerzos y los movimientos repetitivos en condiciones de inestabilidad aumentan el riesgo de lesiones musculoesquel\u00e9ticas y pueden contribuir indirectamente a ca\u00eddas.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, existen riesgos secundarios como <strong>exposici\u00f3n a condiciones clim\u00e1ticas adversas<\/strong>, <strong>atrapamientos<\/strong>, <strong>golpes contra objetos<\/strong> o <strong>vuelco de equipos de elevaci\u00f3n<\/strong> que tambi\u00e9n deben ser considerados en la evaluaci\u00f3n de riesgos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFCuales_son_las_normas_para_trabajar_en_altura\"><\/span><strong>\u00bfCu\u00e1les son las normas para trabajar en altura?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La normativa espa\u00f1ola establece una serie de requisitos fundamentales para garantizar la seguridad en los trabajos en altura. Estas normas incluyen:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Requisitos para los trabajadores<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Formaci\u00f3n espec\u00edfica<\/strong>: Todo trabajador que realice tareas en altura debe recibir formaci\u00f3n te\u00f3rica y pr\u00e1ctica sobre los riesgos espec\u00edficos y las medidas preventivas aplicables.<\/li>\n\n\n\n<li><strong>Aptitud m\u00e9dica<\/strong>: Es obligatorio contar con un certificado de aptitud m\u00e9dica espec\u00edfico para trabajos en altura, que garantice que el trabajador no padece v\u00e9rtigo, problemas card\u00edacos u otras condiciones que puedan aumentar el riesgo.<\/li>\n\n\n\n<li><strong>Autorizaci\u00f3n expresa<\/strong>: La empresa debe autorizar formalmente a los trabajadores que pueden realizar tareas en altura, tras verificar su formaci\u00f3n y aptitud.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Medidas de protecci\u00f3n colectiva<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Barandillas de seguridad<\/strong>: Deben instalarse en plataformas, andamios y cualquier superficie de trabajo elevada. Deben tener una altura m\u00ednima de 90 cm, pasamanos, list\u00f3n intermedio y rodapi\u00e9.<\/li>\n\n\n\n<li><strong>Redes de seguridad<\/strong>: Se utilizan para evitar ca\u00eddas o minimizar sus consecuencias en trabajos de construcci\u00f3n y montaje de estructuras.<\/li>\n\n\n\n<li><strong>Sistemas provisionales de protecci\u00f3n de borde<\/strong>: Conformes a la norma UNE-EN 13374, protegen los per\u00edmetros de forjados, cubiertas y aberturas.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Equipos de protecci\u00f3n individual<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Sistemas antica\u00eddas<\/strong>: Incluyen arn\u00e9s antica\u00eddas, dispositivo de anclaje, conectores y absorbedor de energ\u00eda. Deben cumplir con las normas UNE-EN correspondientes.<\/li>\n\n\n\n<li><strong>Sistemas de sujeci\u00f3n o posicionamiento<\/strong>: Permiten al trabajador mantener una posici\u00f3n estable y segura, liberando sus manos para realizar la tarea.<\/li>\n\n\n\n<li><strong>Sistemas de acceso mediante cuerdas<\/strong>: Utilizados en trabajos verticales, consisten en una l\u00ednea de trabajo y una l\u00ednea de seguridad ancladas por separado.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Procedimientos de trabajo seguro<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Planificaci\u00f3n previa<\/strong>: Todo trabajo en altura debe ser planificado, estableciendo los m\u00e9todos, equipos y medidas preventivas necesarias.<\/li>\n\n\n\n<li><strong>Presencia de recurso preventivo<\/strong>: Obligatoria cuando se realizan trabajos con riesgos especialmente graves de ca\u00edda desde altura.<\/li>\n\n\n\n<li><strong>Plan de emergencia y rescate<\/strong>: Debe existir un procedimiento para actuar en caso de accidente o emergencia, incluyendo el rescate de trabajadores suspendidos tras una ca\u00edda.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Medidas_preventivas_para_trabajos_en_altura\"><\/span><strong>Medidas preventivas para trabajos en altura<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para garantizar la seguridad en los trabajos en altura, es fundamental implementar medidas preventivas adaptadas a cada situaci\u00f3n:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Medidas generales<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Evaluar alternativas<\/strong>: Siempre que sea posible, <strong>se debe evitar el trabajo en altura<\/strong>, sustituy\u00e9ndolo por m\u00e9todos alternativos que permitan realizar la tarea desde el nivel del suelo.<\/li>\n\n\n\n<li><strong>Seleccionar equipos adecuados<\/strong>: Utilizar plataformas elevadoras, andamios o escaleras en funci\u00f3n de la naturaleza y duraci\u00f3n del trabajo.<\/li>\n\n\n\n<li><strong>Inspeccionar el entorno<\/strong>: Analizar las condiciones del lugar de trabajo, identificando posibles obst\u00e1culos, l\u00edneas el\u00e9ctricas o superficies inestables.<\/li>\n\n\n\n<li><strong>Considerar las condiciones meteorol\u00f3gicas<\/strong>: Suspender los trabajos en caso de lluvia intensa, nieve, hielo o viento fuerte.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Medidas espec\u00edficas seg\u00fan el tipo de trabajo<\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Trabajos con andamios<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Montaje por personal especializado<\/strong> con formaci\u00f3n espec\u00edfica seg\u00fan RD 2177\/2004.<\/li>\n\n\n\n<li><strong>Inspecci\u00f3n diaria<\/strong> antes de comenzar los trabajos y tras cualquier modificaci\u00f3n.<\/li>\n\n\n\n<li><strong>Nivelaci\u00f3n y estabilidad<\/strong> mediante bases regulables sobre superficies resistentes y husillos de nivelaci\u00f3n.<\/li>\n\n\n\n<li><strong>Arriostramientos adecuados<\/strong> a elementos fijos de la estructura para evitar vuelcos.<\/li>\n\n\n\n<li>Uso de <strong>plataformas completas con barandillas y rodapi\u00e9s<\/strong> en todo el per\u00edmetro.<\/li>\n\n\n\n<li><strong>Acceso seguro<\/strong> mediante escaleras interiores, nunca trepando por la estructura.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Trabajos en cubiertas y tejados<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Estudio previo<\/strong> de la resistencia de la superficie y utilizaci\u00f3n de pasarelas de reparto de cargas en cubiertas fr\u00e1giles.<\/li>\n\n\n\n<li><strong>Protecci\u00f3n perimetral<\/strong> mediante barandillas o sistemas provisionales de protecci\u00f3n de borde.<\/li>\n\n\n\n<li><strong>L\u00edneas de vida<\/strong> horizontales instaladas por personal competente y verificadas antes de su uso.<\/li>\n\n\n\n<li><strong>Restricci\u00f3n de acceso<\/strong> a zonas no protegidas mediante se\u00f1alizaci\u00f3n y barreras f\u00edsicas.<\/li>\n\n\n\n<li>Uso de <strong>arn\u00e9s antica\u00eddas<\/strong> conectado a puntos de anclaje fiables o l\u00edneas de vida.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Trabajos con escaleras manuales<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Inspecci\u00f3n visual<\/strong> antes de cada uso, verificando el estado de largueros, pelda\u00f1os y sistemas de sujeci\u00f3n.<\/li>\n\n\n\n<li><strong>\u00c1ngulo de inclinaci\u00f3n adecuado<\/strong>, aproximadamente 75\u00ba (relaci\u00f3n 1:4 entre separaci\u00f3n de la base y altura).<\/li>\n\n\n\n<li><strong>Sobresalir al menos 1 metro<\/strong> por encima del punto de apoyo superior.<\/li>\n\n\n\n<li><strong>Asegurar la estabilidad<\/strong> mediante sistemas antideslizantes en la base y sujeci\u00f3n o fijaci\u00f3n en la parte superior.<\/li>\n\n\n\n<li><strong>Limitar el uso<\/strong> a trabajos de corta duraci\u00f3n y que no requieran ejercer fuerzas laterales importantes.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Equipos_de_proteccion_individual_para_trabajos_en_altura\"><\/span><strong>Equipos de protecci\u00f3n individual para trabajos en altura<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los equipos de protecci\u00f3n individual (EPIs) son la \u00faltima barrera de seguridad cuando las medidas colectivas no son suficientes. Los principales EPIs para trabajos en altura son:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Arn\u00e9s antica\u00eddas<\/strong>: Elemento fundamental que distribuye las fuerzas de impacto en caso de ca\u00edda. Debe ajustarse correctamente al cuerpo del trabajador.<\/li>\n\n\n\n<li><strong>Dispositivos de anclaje<\/strong>: Incluyen puntos fijos, l\u00edneas de vida horizontales o verticales y dispositivos provisionales transportables.<\/li>\n\n\n\n<li><strong>Conectores<\/strong>: Mosquetones y ganchos que permiten unir los diferentes elementos del sistema antica\u00eddas.<\/li>\n\n\n\n<li><strong>Absorbedores de energ\u00eda<\/strong>: Reducen la fuerza de impacto sobre el cuerpo del trabajador en caso de ca\u00edda.<\/li>\n\n\n\n<li><strong>Dispositivos antica\u00eddas retr\u00e1ctiles<\/strong>: Permiten libertad de movimiento dentro de un \u00e1rea determinada y se bloquean autom\u00e1ticamente en caso de ca\u00edda.<\/li>\n\n\n\n<li><strong>Casco con barboquejo<\/strong>: Protege la cabeza en caso de impacto y evita que el casco se desprenda durante una ca\u00edda.<\/li>\n\n\n\n<li><strong>Calzado de seguridad antideslizante<\/strong>: Proporciona agarre y estabilidad en superficies resbaladizas.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Todos estos equipos deben estar <strong>certificados seg\u00fan las normas europeas<\/strong> correspondientes y ser sometidos a <strong>inspecciones peri\u00f3dicas<\/strong> documentadas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Formacion_necesaria_para_trabajos_en_altura\"><\/span><strong>Formaci\u00f3n necesaria para trabajos en altura<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La formaci\u00f3n es un pilar fundamental para prevenir accidentes en trabajos en altura. Esta debe incluir:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Formaci\u00f3n te\u00f3rica<\/strong> sobre riesgos espec\u00edficos, normativa aplicable y medidas preventivas.<\/li>\n\n\n\n<li><strong>Formaci\u00f3n pr\u00e1ctica<\/strong> en el uso correcto de equipos de protecci\u00f3n individual y colectiva.<\/li>\n\n\n\n<li><strong>Entrenamiento en procedimientos de emergencia y rescate<\/strong> para situaciones cr\u00edticas.<\/li>\n\n\n\n<li><strong>Actualizaci\u00f3n peri\u00f3dica<\/strong> de conocimientos y habilidades, especialmente cuando se introducen nuevos equipos o t\u00e9cnicas.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">La duraci\u00f3n y contenido de la formaci\u00f3n depender\u00e1 del tipo de trabajo en altura a realizar, pero debe ser <strong>impartida por personal cualificado<\/strong> y <strong>documentada adecuadamente<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Preguntas_frecuentes_sobre_trabajos_en_altura\"><\/span><strong>Preguntas frecuentes sobre trabajos en altura<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<div class=\"schema-faq wp-block-yoast-faq-block\"><div class=\"schema-faq-section\" id=\"faq-question-1777361019085\"><strong class=\"schema-faq-question\"><strong>\u00bfCu\u00e1ndo se considera trabajo en altura normativa?<\/strong><\/strong> <p class=\"schema-faq-answer\">Seg\u00fan la normativa espa\u00f1ola, <strong>se considera trabajo en altura cualquier actividad realizada a 2 o m\u00e1s metros del suelo<\/strong> donde existe riesgo de ca\u00edda. Esta definici\u00f3n, aunque no aparece expl\u00edcitamente en la legislaci\u00f3n, es la com\u00fanmente aceptada en el \u00e1mbito de la prevenci\u00f3n de riesgos laborales y sirve como referencia para la aplicaci\u00f3n de medidas preventivas.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1777361042143\"><strong class=\"schema-faq-question\"><strong>\u00bfCu\u00e1les son los tipos de trabajos en altura?<\/strong><\/strong> <p class=\"schema-faq-answer\">Los principales tipos de trabajos en altura incluyen:<br>&#8211;<strong>Trabajos en andamios y plataformas elevadoras<\/strong><br><strong>-Trabajos en postes, torres y antenas<\/strong><br><strong>-Trabajos en tejados y cubiertas<\/strong><br><strong>-Trabajos verticales o con t\u00e9cnicas de acceso mediante cuerdas<\/strong><br><strong>-Trabajos con escaleras manuales<\/strong><br><strong>-Trabajos de montaje y desmontaje de estructuras temporales<\/strong><\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1777361079006\"><strong class=\"schema-faq-question\"><strong>\u00bfCu\u00e1les son las normas para trabajar en altura?<\/strong><\/strong> <p class=\"schema-faq-answer\">Las principales normas para trabajar en altura establecen:<br>&#8211;<strong>Formaci\u00f3n espec\u00edfica<\/strong> te\u00f3rica y pr\u00e1ctica obligatoria para todos los trabajadores<br><strong>-Certificado de aptitud m\u00e9dica<\/strong> espec\u00edfico para trabajos en altura<br><strong>-Autorizaci\u00f3n expresa<\/strong> por parte de la empresa<br><strong>-Uso de protecciones colectivas<\/strong> (barandillas, redes) como primera opci\u00f3n<br><strong>-Equipos de protecci\u00f3n individual<\/strong> certificados cuando no sean suficientes las protecciones colectivas<br><strong>-Presencia de recurso preventivo<\/strong> en trabajos con riesgos especialmente graves<br><strong>-Plan de emergencia y rescate<\/strong> para actuar en caso de accidente<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1777361134381\"><strong class=\"schema-faq-question\"><strong>\u00bfCu\u00e1les son los 4 riesgos en un trabajo en altura?<\/strong><\/strong> <p class=\"schema-faq-answer\">Los cuatro riesgos principales en trabajos en altura son:<br>&#8211;<strong>Ca\u00eddas a distinto nivel<\/strong>: El riesgo m\u00e1s grave y frecuente<br><strong>-Ca\u00edda de objetos sobre personas<\/strong>: Herramientas, materiales o equipos que pueden lesionar a personas situadas en niveles inferiores<br><strong>-Contactos el\u00e9ctricos<\/strong>: Especialmente en trabajos cerca de l\u00edneas o instalaciones el\u00e9ctricas<br><strong>-Riesgos posturales y ergon\u00f3micos<\/strong>: Posturas forzadas y sobreesfuerzos que pueden contribuir indirectamente a ca\u00eddas<\/p> <\/div> <\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Conclusiones_claves_para_la_seguridad_en_trabajos_en_altura\"><\/span><strong>Conclusiones: claves para la seguridad en trabajos en altura<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para garantizar la seguridad en los trabajos en altura, es esencial recordar los tres pilares fundamentales:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Prevenci\u00f3n<\/strong>: Evitar los riesgos mediante planificaci\u00f3n, formaci\u00f3n y selecci\u00f3n adecuada de equipos.<\/li>\n\n\n\n<li><strong>Protecci\u00f3n<\/strong>: Implementar medidas colectivas e individuales que minimicen las consecuencias en caso de accidente.<\/li>\n\n\n\n<li><strong>Salvamento<\/strong>: Disponer de procedimientos de emergencia y rescate efectivos para actuar r\u00e1pidamente en caso de accidente.<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Puntos clave a recordar:<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Se considera trabajo en altura cualquier actividad con riesgo de ca\u00edda a distinto nivel, especialmente a partir de 2 metros.<\/li>\n\n\n\n<li>La planificaci\u00f3n previa, la evaluaci\u00f3n de riesgos y la elecci\u00f3n del equipo adecuado son esenciales antes de iniciar la tarea.<\/li>\n\n\n\n<li>Las protecciones colectivas deben priorizarse frente a los equipos de protecci\u00f3n individual siempre que sea posible.<\/li>\n\n\n\n<li>La formaci\u00f3n, la autorizaci\u00f3n del trabajador y un plan de rescate son imprescindibles para trabajar con seguridad.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Los trabajos en altura seguir\u00e1n siendo necesarios en numerosos sectores, pero <strong>con una adecuada gesti\u00f3n preventiva<\/strong>, formaci\u00f3n de calidad y utilizaci\u00f3n de equipos apropiados, es posible reducir significativamente el n\u00famero y gravedad de los accidentes asociados a estos trabajos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La seguridad en los trabajos en altura no es simplemente una obligaci\u00f3n legal, sino una <strong>responsabilidad compartida<\/strong> entre empresarios y trabajadores que contribuye a preservar la vida y la salud de quienes desempe\u00f1an estas arriesgadas tareas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los trabajos en altura representan una de las actividades laborales con mayor \u00edndice de siniestralidad en Espa\u00f1a. A pesar de los avances normativos y t\u00e9cnicos de los \u00faltimos a\u00f1os, siguen siendo causa de accidentes graves y mortales en diversos sectores profesionales. Esta gu\u00eda completa aborda todos los aspectos fundamentales que debes conocer sobre los trabajos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":35496,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":"","tve_updated_post":"","tve_custom_css":"","tve_user_custom_css":"","tve_globals":{},"tcb2_ready":0,"tcb_editor_enabled":0,"tve_landing_page":"","_tve_header":"","_tve_footer":""},"categories":[32,31],"tags":[],"class_list":["post-35493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-normativa","category-prevencion-de-riesgos-laborales","post-wrapper","thrv_wrapper"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trabajos en Altura: Normativa, Riesgos y Prevenci\u00f3n - CTAIMA<\/title>\n<meta name=\"description\" content=\"\u00bfCu\u00e1ndo se considera trabajo en alturas? Descubre la normativa actual, los requisitos legales RD 2177\/2004 y medidas preventivas obligatorias\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trabajos en Altura: Normativa, Riesgos y Prevenci\u00f3n - CTAIMA\" \/>\n<meta property=\"og:description\" content=\"\u00bfCu\u00e1ndo se considera trabajo en alturas? Descubre la normativa actual, los requisitos legales RD 2177\/2004 y medidas preventivas obligatorias\" \/>\n<meta property=\"og:url\" content=\"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/\" \/>\n<meta property=\"og:site_name\" content=\"Twind - Plataforma de Coordinaci\u00f3n de Actividades Empresariales\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-27T08:02:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-29T10:37:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/twind.io\/es\/wp-content\/uploads\/2025\/02\/trabajador-seguridad-altura-plataforma-industrial.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Twind Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Twind Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/trabajos-en-altura-normativa-prevencion-rd-2177\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/trabajos-en-altura-normativa-prevencion-rd-2177\\\/\"},\"author\":{\"name\":\"Twind Team\",\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/#\\\/schema\\\/person\\\/4f69058786bd1debb9748aaeb897a69c\"},\"headline\":\"Trabajos en Altura: Normativa, Riesgos y Prevenci\u00f3n\",\"datePublished\":\"2025-02-27T08:02:13+00:00\",\"dateModified\":\"2026-06-29T10:37:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/trabajos-en-altura-normativa-prevencion-rd-2177\\\/\"},\"wordCount\":2291,\"image\":{\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/trabajos-en-altura-normativa-prevencion-rd-2177\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/twind.io\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/trabajador-seguridad-altura-plataforma-industrial.webp\",\"articleSection\":[\"Normativa\",\"Prevenci\u00f3n de Riesgos Laborales\"],\"inLanguage\":\"es\"},{\"@type\":[\"WebPage\",\"FAQPage\"],\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/trabajos-en-altura-normativa-prevencion-rd-2177\\\/\",\"url\":\"https:\\\/\\\/twind.io\\\/es\\\/trabajos-en-altura-normativa-prevencion-rd-2177\\\/\",\"name\":\"Trabajos en Altura: Normativa, Riesgos y Prevenci\u00f3n - CTAIMA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/trabajos-en-altura-normativa-prevencion-rd-2177\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/trabajos-en-altura-normativa-prevencion-rd-2177\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/twind.io\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/trabajador-seguridad-altura-plataforma-industrial.webp\",\"datePublished\":\"2025-02-27T08:02:13+00:00\",\"dateModified\":\"2026-06-29T10:37:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/#\\\/schema\\\/person\\\/4f69058786bd1debb9748aaeb897a69c\"},\"description\":\"\u00bfCu\u00e1ndo se considera trabajo en alturas? Descubre la normativa actual, los requisitos legales RD 2177\\\/2004 y medidas preventivas obligatorias\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/trabajos-en-altura-normativa-prevencion-rd-2177\\\/#breadcrumb\"},\"mainEntity\":[{\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/trabajos-en-altura-normativa-prevencion-rd-2177\\\/#faq-question-1777361019085\"},{\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/trabajos-en-altura-normativa-prevencion-rd-2177\\\/#faq-question-1777361042143\"},{\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/trabajos-en-altura-normativa-prevencion-rd-2177\\\/#faq-question-1777361079006\"},{\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/trabajos-en-altura-normativa-prevencion-rd-2177\\\/#faq-question-1777361134381\"}],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/twind.io\\\/es\\\/trabajos-en-altura-normativa-prevencion-rd-2177\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/trabajos-en-altura-normativa-prevencion-rd-2177\\\/#primaryimage\",\"url\":\"https:\\\/\\\/twind.io\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/trabajador-seguridad-altura-plataforma-industrial.webp\",\"contentUrl\":\"https:\\\/\\\/twind.io\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/trabajador-seguridad-altura-plataforma-industrial.webp\",\"width\":1200,\"height\":800,\"caption\":\"Operario con casco de seguridad y chaleco reflectante en trabajos en altura sobre plataforma con barandillas de protecci\u00f3n conforme a normativa RD 2177\\\/2004\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/trabajos-en-altura-normativa-prevencion-rd-2177\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/twind.io\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trabajos en Altura: Normativa, Riesgos y Prevenci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/twind.io\\\/es\\\/\",\"name\":\"Twind - Plataforma de Coordinaci\u00f3n de Actividades Empresariales\",\"description\":\"Coordina los procesos de gesti\u00f3n documental y control de contratistas y proveedores, respetando la normativa en materia de Seguridad y Salud en el Trabajo.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/twind.io\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/#\\\/schema\\\/person\\\/4f69058786bd1debb9748aaeb897a69c\",\"name\":\"Twind Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g\",\"caption\":\"Twind Team\"},\"description\":\"Comunicaci\u00f3n y contenidos\",\"sameAs\":[\"https:\\\/\\\/twind.io\\\/es\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/twind-io\\\/\"],\"url\":\"https:\\\/\\\/twind.io\\\/es\\\/author\\\/rrios_6eq9khcx\\\/\"},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/trabajos-en-altura-normativa-prevencion-rd-2177\\\/#faq-question-1777361019085\",\"position\":1,\"url\":\"https:\\\/\\\/twind.io\\\/es\\\/trabajos-en-altura-normativa-prevencion-rd-2177\\\/#faq-question-1777361019085\",\"name\":\"\u00bfCu\u00e1ndo se considera trabajo en altura normativa?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Seg\u00fan la normativa espa\u00f1ola, <strong>se considera trabajo en altura cualquier actividad realizada a 2 o m\u00e1s metros del suelo<\\\/strong> donde existe riesgo de ca\u00edda. Esta definici\u00f3n, aunque no aparece expl\u00edcitamente en la legislaci\u00f3n, es la com\u00fanmente aceptada en el \u00e1mbito de la prevenci\u00f3n de riesgos laborales y sirve como referencia para la aplicaci\u00f3n de medidas preventivas.\",\"inLanguage\":\"es\"},\"inLanguage\":\"es\"},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/trabajos-en-altura-normativa-prevencion-rd-2177\\\/#faq-question-1777361042143\",\"position\":2,\"url\":\"https:\\\/\\\/twind.io\\\/es\\\/trabajos-en-altura-normativa-prevencion-rd-2177\\\/#faq-question-1777361042143\",\"name\":\"\u00bfCu\u00e1les son los tipos de trabajos en altura?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Los principales tipos de trabajos en altura incluyen:<br>-<strong>Trabajos en andamios y plataformas elevadoras<\\\/strong><br><strong>-Trabajos en postes, torres y antenas<\\\/strong><br><strong>-Trabajos en tejados y cubiertas<\\\/strong><br><strong>-Trabajos verticales o con t\u00e9cnicas de acceso mediante cuerdas<\\\/strong><br><strong>-Trabajos con escaleras manuales<\\\/strong><br><strong>-Trabajos de montaje y desmontaje de estructuras temporales<\\\/strong>\",\"inLanguage\":\"es\"},\"inLanguage\":\"es\"},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/trabajos-en-altura-normativa-prevencion-rd-2177\\\/#faq-question-1777361079006\",\"position\":3,\"url\":\"https:\\\/\\\/twind.io\\\/es\\\/trabajos-en-altura-normativa-prevencion-rd-2177\\\/#faq-question-1777361079006\",\"name\":\"\u00bfCu\u00e1les son las normas para trabajar en altura?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Las principales normas para trabajar en altura establecen:<br>-<strong>Formaci\u00f3n espec\u00edfica<\\\/strong> te\u00f3rica y pr\u00e1ctica obligatoria para todos los trabajadores<br><strong>-Certificado de aptitud m\u00e9dica<\\\/strong> espec\u00edfico para trabajos en altura<br><strong>-Autorizaci\u00f3n expresa<\\\/strong> por parte de la empresa<br><strong>-Uso de protecciones colectivas<\\\/strong> (barandillas, redes) como primera opci\u00f3n<br><strong>-Equipos de protecci\u00f3n individual<\\\/strong> certificados cuando no sean suficientes las protecciones colectivas<br><strong>-Presencia de recurso preventivo<\\\/strong> en trabajos con riesgos especialmente graves<br><strong>-Plan de emergencia y rescate<\\\/strong> para actuar en caso de accidente\",\"inLanguage\":\"es\"},\"inLanguage\":\"es\"},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/trabajos-en-altura-normativa-prevencion-rd-2177\\\/#faq-question-1777361134381\",\"position\":4,\"url\":\"https:\\\/\\\/twind.io\\\/es\\\/trabajos-en-altura-normativa-prevencion-rd-2177\\\/#faq-question-1777361134381\",\"name\":\"\u00bfCu\u00e1les son los 4 riesgos en un trabajo en altura?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Los cuatro riesgos principales en trabajos en altura son:<br>-<strong>Ca\u00eddas a distinto nivel<\\\/strong>: El riesgo m\u00e1s grave y frecuente<br><strong>-Ca\u00edda de objetos sobre personas<\\\/strong>: Herramientas, materiales o equipos que pueden lesionar a personas situadas en niveles inferiores<br><strong>-Contactos el\u00e9ctricos<\\\/strong>: Especialmente en trabajos cerca de l\u00edneas o instalaciones el\u00e9ctricas<br><strong>-Riesgos posturales y ergon\u00f3micos<\\\/strong>: Posturas forzadas y sobreesfuerzos que pueden contribuir indirectamente a ca\u00eddas\",\"inLanguage\":\"es\"},\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trabajos en Altura: Normativa, Riesgos y Prevenci\u00f3n - CTAIMA","description":"\u00bfCu\u00e1ndo se considera trabajo en alturas? Descubre la normativa actual, los requisitos legales RD 2177\/2004 y medidas preventivas obligatorias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/","og_locale":"es_ES","og_type":"article","og_title":"Trabajos en Altura: Normativa, Riesgos y Prevenci\u00f3n - CTAIMA","og_description":"\u00bfCu\u00e1ndo se considera trabajo en alturas? Descubre la normativa actual, los requisitos legales RD 2177\/2004 y medidas preventivas obligatorias","og_url":"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/","og_site_name":"Twind - Plataforma de Coordinaci\u00f3n de Actividades Empresariales","article_published_time":"2025-02-27T08:02:13+00:00","article_modified_time":"2026-06-29T10:37:34+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/twind.io\/es\/wp-content\/uploads\/2025\/02\/trabajador-seguridad-altura-plataforma-industrial.webp","type":"image\/webp"}],"author":"Twind Team","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Twind Team","Tiempo de lectura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/#article","isPartOf":{"@id":"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/"},"author":{"name":"Twind Team","@id":"https:\/\/twind.io\/es\/#\/schema\/person\/4f69058786bd1debb9748aaeb897a69c"},"headline":"Trabajos en Altura: Normativa, Riesgos y Prevenci\u00f3n","datePublished":"2025-02-27T08:02:13+00:00","dateModified":"2026-06-29T10:37:34+00:00","mainEntityOfPage":{"@id":"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/"},"wordCount":2291,"image":{"@id":"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/#primaryimage"},"thumbnailUrl":"https:\/\/twind.io\/es\/wp-content\/uploads\/2025\/02\/trabajador-seguridad-altura-plataforma-industrial.webp","articleSection":["Normativa","Prevenci\u00f3n de Riesgos Laborales"],"inLanguage":"es"},{"@type":["WebPage","FAQPage"],"@id":"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/","url":"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/","name":"Trabajos en Altura: Normativa, Riesgos y Prevenci\u00f3n - CTAIMA","isPartOf":{"@id":"https:\/\/twind.io\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/#primaryimage"},"image":{"@id":"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/#primaryimage"},"thumbnailUrl":"https:\/\/twind.io\/es\/wp-content\/uploads\/2025\/02\/trabajador-seguridad-altura-plataforma-industrial.webp","datePublished":"2025-02-27T08:02:13+00:00","dateModified":"2026-06-29T10:37:34+00:00","author":{"@id":"https:\/\/twind.io\/es\/#\/schema\/person\/4f69058786bd1debb9748aaeb897a69c"},"description":"\u00bfCu\u00e1ndo se considera trabajo en alturas? Descubre la normativa actual, los requisitos legales RD 2177\/2004 y medidas preventivas obligatorias","breadcrumb":{"@id":"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/#breadcrumb"},"mainEntity":[{"@id":"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/#faq-question-1777361019085"},{"@id":"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/#faq-question-1777361042143"},{"@id":"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/#faq-question-1777361079006"},{"@id":"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/#faq-question-1777361134381"}],"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/#primaryimage","url":"https:\/\/twind.io\/es\/wp-content\/uploads\/2025\/02\/trabajador-seguridad-altura-plataforma-industrial.webp","contentUrl":"https:\/\/twind.io\/es\/wp-content\/uploads\/2025\/02\/trabajador-seguridad-altura-plataforma-industrial.webp","width":1200,"height":800,"caption":"Operario con casco de seguridad y chaleco reflectante en trabajos en altura sobre plataforma con barandillas de protecci\u00f3n conforme a normativa RD 2177\/2004"},{"@type":"BreadcrumbList","@id":"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/twind.io\/es\/"},{"@type":"ListItem","position":2,"name":"Trabajos en Altura: Normativa, Riesgos y Prevenci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/twind.io\/es\/#website","url":"https:\/\/twind.io\/es\/","name":"Twind - Plataforma de Coordinaci\u00f3n de Actividades Empresariales","description":"Coordina los procesos de gesti\u00f3n documental y control de contratistas y proveedores, respetando la normativa en materia de Seguridad y Salud en el Trabajo.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/twind.io\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/twind.io\/es\/#\/schema\/person\/4f69058786bd1debb9748aaeb897a69c","name":"Twind Team","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g","caption":"Twind Team"},"description":"Comunicaci\u00f3n y contenidos","sameAs":["https:\/\/twind.io\/es\/","https:\/\/www.linkedin.com\/showcase\/twind-io\/"],"url":"https:\/\/twind.io\/es\/author\/rrios_6eq9khcx\/"},{"@type":"Question","@id":"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/#faq-question-1777361019085","position":1,"url":"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/#faq-question-1777361019085","name":"\u00bfCu\u00e1ndo se considera trabajo en altura normativa?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Seg\u00fan la normativa espa\u00f1ola, <strong>se considera trabajo en altura cualquier actividad realizada a 2 o m\u00e1s metros del suelo<\/strong> donde existe riesgo de ca\u00edda. Esta definici\u00f3n, aunque no aparece expl\u00edcitamente en la legislaci\u00f3n, es la com\u00fanmente aceptada en el \u00e1mbito de la prevenci\u00f3n de riesgos laborales y sirve como referencia para la aplicaci\u00f3n de medidas preventivas.","inLanguage":"es"},"inLanguage":"es"},{"@type":"Question","@id":"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/#faq-question-1777361042143","position":2,"url":"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/#faq-question-1777361042143","name":"\u00bfCu\u00e1les son los tipos de trabajos en altura?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Los principales tipos de trabajos en altura incluyen:<br>-<strong>Trabajos en andamios y plataformas elevadoras<\/strong><br><strong>-Trabajos en postes, torres y antenas<\/strong><br><strong>-Trabajos en tejados y cubiertas<\/strong><br><strong>-Trabajos verticales o con t\u00e9cnicas de acceso mediante cuerdas<\/strong><br><strong>-Trabajos con escaleras manuales<\/strong><br><strong>-Trabajos de montaje y desmontaje de estructuras temporales<\/strong>","inLanguage":"es"},"inLanguage":"es"},{"@type":"Question","@id":"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/#faq-question-1777361079006","position":3,"url":"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/#faq-question-1777361079006","name":"\u00bfCu\u00e1les son las normas para trabajar en altura?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Las principales normas para trabajar en altura establecen:<br>-<strong>Formaci\u00f3n espec\u00edfica<\/strong> te\u00f3rica y pr\u00e1ctica obligatoria para todos los trabajadores<br><strong>-Certificado de aptitud m\u00e9dica<\/strong> espec\u00edfico para trabajos en altura<br><strong>-Autorizaci\u00f3n expresa<\/strong> por parte de la empresa<br><strong>-Uso de protecciones colectivas<\/strong> (barandillas, redes) como primera opci\u00f3n<br><strong>-Equipos de protecci\u00f3n individual<\/strong> certificados cuando no sean suficientes las protecciones colectivas<br><strong>-Presencia de recurso preventivo<\/strong> en trabajos con riesgos especialmente graves<br><strong>-Plan de emergencia y rescate<\/strong> para actuar en caso de accidente","inLanguage":"es"},"inLanguage":"es"},{"@type":"Question","@id":"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/#faq-question-1777361134381","position":4,"url":"https:\/\/twind.io\/es\/trabajos-en-altura-normativa-prevencion-rd-2177\/#faq-question-1777361134381","name":"\u00bfCu\u00e1les son los 4 riesgos en un trabajo en altura?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Los cuatro riesgos principales en trabajos en altura son:<br>-<strong>Ca\u00eddas a distinto nivel<\/strong>: El riesgo m\u00e1s grave y frecuente<br><strong>-Ca\u00edda de objetos sobre personas<\/strong>: Herramientas, materiales o equipos que pueden lesionar a personas situadas en niveles inferiores<br><strong>-Contactos el\u00e9ctricos<\/strong>: Especialmente en trabajos cerca de l\u00edneas o instalaciones el\u00e9ctricas<br><strong>-Riesgos posturales y ergon\u00f3micos<\/strong>: Posturas forzadas y sobreesfuerzos que pueden contribuir indirectamente a ca\u00eddas","inLanguage":"es"},"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/twind.io\/es\/wp-json\/wp\/v2\/posts\/35493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/twind.io\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/twind.io\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/twind.io\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/twind.io\/es\/wp-json\/wp\/v2\/comments?post=35493"}],"version-history":[{"count":5,"href":"https:\/\/twind.io\/es\/wp-json\/wp\/v2\/posts\/35493\/revisions"}],"predecessor-version":[{"id":38787,"href":"https:\/\/twind.io\/es\/wp-json\/wp\/v2\/posts\/35493\/revisions\/38787"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/twind.io\/es\/wp-json\/wp\/v2\/media\/35496"}],"wp:attachment":[{"href":"https:\/\/twind.io\/es\/wp-json\/wp\/v2\/media?parent=35493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/twind.io\/es\/wp-json\/wp\/v2\/categories?post=35493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/twind.io\/es\/wp-json\/wp\/v2\/tags?post=35493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}