{"id":4118,"date":"2025-06-03T14:37:15","date_gmt":"2025-06-03T14:37:15","guid":{"rendered":"https:\/\/twind.io\/es\/?p=4118"},"modified":"2026-05-26T09:56:29","modified_gmt":"2026-05-26T09:56:29","slug":"coordinador-seguridad-salud","status":"publish","type":"post","link":"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/","title":{"rendered":"Coordinador de Seguridad y Salud: Todo lo que Necesitas Saber"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El <strong>coordinador de seguridad y salud<\/strong> es una figura esencial en el sector de la construcci\u00f3n en Espa\u00f1a. Si est\u00e1s buscando informaci\u00f3n completa sobre esta profesi\u00f3n, sus funciones, requisitos y obligaciones, has llegado al lugar correcto. En esta gu\u00eda exhaustiva, te explicaremos todo lo que necesitas saber sobre la <strong>coordinaci\u00f3n de seguridad y salud<\/strong> en obras de construcci\u00f3n.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Tabla de contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #6b6b6b;color:#6b6b6b\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #6b6b6b;color:#6b6b6b\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#%C2%BFQue_es_un_Coordinador_de_Seguridad_y_Salud\" >\u00bfQu\u00e9 es un Coordinador de Seguridad y Salud?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#%C2%BFCuando_es_Obligatorio_Designar_un_Coordinador_de_Seguridad_y_Salud\" >\u00bfCu\u00e1ndo es Obligatorio Designar un Coordinador de Seguridad y Salud?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#Funciones_del_Coordinador_de_Seguridad_y_Salud\" >Funciones del Coordinador de Seguridad y Salud<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#Requisitos_para_ser_Coordinador_de_Seguridad_y_Salud\" >Requisitos para ser Coordinador de Seguridad y Salud<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#%C2%BFQuien_Designa_al_Coordinador_de_Seguridad_y_Salud\" >\u00bfQui\u00e9n Designa al Coordinador de Seguridad y Salud?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#Documentacion_y_Registros_Obligatorios\" >Documentaci\u00f3n y Registros Obligatorios<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#Diferencias_entre_Coordinador_en_Fase_de_Proyecto_y_Ejecucion\" >Diferencias entre Coordinador en Fase de Proyecto y Ejecuci\u00f3n<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#Preguntas_Frecuentes_sobre_el_Coordinador_de_Seguridad_y_Salud\" >Preguntas Frecuentes sobre el Coordinador de Seguridad y Salud<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#Importancia_del_Coordinador_en_la_Prevencion_de_Accidentes\" >Importancia del Coordinador en la Prevenci\u00f3n de Accidentes<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#Herramientas_y_Software_para_Coordinadores\" >Herramientas y Software para Coordinadores<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#Formacion_Continua_y_Actualizacion\" >Formaci\u00f3n Continua y Actualizaci\u00f3n<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#Conclusiones\" >Conclusiones<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFQue_es_un_Coordinador_de_Seguridad_y_Salud\"><\/span><strong>\u00bfQu\u00e9 es un Coordinador de Seguridad y Salud?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El <strong>coordinador de seguridad y salud<\/strong> es un <strong>t\u00e9cnico competente designado por el promotor<\/strong> de una obra para garantizar que se cumplan todas las medidas de prevenci\u00f3n de riesgos laborales durante las fases de proyecto y ejecuci\u00f3n de obras de construcci\u00f3n. Esta figura est\u00e1 regulada por el <strong><a href=\"https:\/\/twind.io\/es\/rd-1627-97-seguridad-obras-construccion\/\">Real Decreto 1627\/1997<\/a><\/strong>, que establece las disposiciones m\u00ednimas de seguridad y salud en las obras de construcci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Definici\u00f3n Legal y Marco Normativo<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan el <strong><a href=\"https:\/\/twind.io\/es\/rd-1627-97-seguridad-obras-construccion\/\">RD 1627\/97<\/a><\/strong>, el coordinador en materia de seguridad y salud es:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>En fase de proyecto<\/strong>: El t\u00e9cnico competente designado por el promotor para coordinar la aplicaci\u00f3n de los principios preventivos durante la elaboraci\u00f3n del proyecto<\/li>\n\n\n\n<li><strong>En fase de ejecuci\u00f3n<\/strong>: El t\u00e9cnico competente integrado en la Direcci\u00f3n Facultativa, designado por el promotor para llevar a cabo las tareas de coordinaci\u00f3n preventiva durante la obra<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFCuando_es_Obligatorio_Designar_un_Coordinador_de_Seguridad_y_Salud\"><\/span><strong>\u00bfCu\u00e1ndo es Obligatorio Designar un Coordinador de Seguridad y Salud?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La designaci\u00f3n de un <strong>coordinador seguridad y salud<\/strong> es <strong>obligatoria<\/strong> en los siguientes casos:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>En Fase de Proyecto<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u2705 <strong>Cuando intervienen varios proyectistas<\/strong> en la elaboraci\u00f3n del proyecto de obra<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>En Fase de Ejecuci\u00f3n<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u2705 Cuando en la obra <strong>interviene m\u00e1s de una empresa<\/strong> \u2705 Cuando participa <strong>una empresa y trabajadores aut\u00f3nomos<\/strong> \u2705 Cuando intervienen <strong>diversos trabajadores aut\u00f3nomos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Importante<\/strong>: La obligaci\u00f3n existe <strong>independientemente<\/strong> de:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El tama\u00f1o de la obra<\/li>\n\n\n\n<li>La duraci\u00f3n de los trabajos<\/li>\n\n\n\n<li>Si existe o no proyecto de obra<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Funciones_del_Coordinador_de_Seguridad_y_Salud\"><\/span><strong>Funciones del Coordinador de Seguridad y Salud<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Las <strong>funciones del coordinador de seguridad y salud<\/strong> var\u00edan seg\u00fan la fase en la que se encuentre la obra:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Funciones en Fase de Proyecto<\/strong><\/h3>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Coordinar la aplicaci\u00f3n de principios preventivos<\/strong> en:\n<ul class=\"wp-block-list\">\n<li>La toma de decisiones t\u00e9cnicas y organizativas<\/li>\n\n\n\n<li>La estimaci\u00f3n de la duraci\u00f3n de los trabajos<\/li>\n\n\n\n<li>La planificaci\u00f3n de las fases de obra<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Elaborar o hacer que se elabore<\/strong> el Estudio de Seguridad y Salud o el Estudio B\u00e1sico<\/li>\n\n\n\n<li><strong>Integrar la prevenci\u00f3n<\/strong> desde el dise\u00f1o del proyecto<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Funciones en Fase de Ejecuci\u00f3n<\/strong><\/h3>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Coordinar la aplicaci\u00f3n de principios generales de prevenci\u00f3n<\/strong>:\n<ul class=\"wp-block-list\">\n<li>Mantenimiento del orden y limpieza en obra<\/li>\n\n\n\n<li>Elecci\u00f3n de ubicaci\u00f3n de puestos y \u00e1reas de trabajo<\/li>\n\n\n\n<li>Manipulaci\u00f3n de materiales<\/li>\n\n\n\n<li>Control de instalaciones y medios auxiliares<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Coordinar las actividades de la obra<\/strong>:\n<ul class=\"wp-block-list\">\n<li>Aplicaci\u00f3n coherente del Plan de Seguridad y Salud<\/li>\n\n\n\n<li>Coordinaci\u00f3n entre contratistas, subcontratistas y aut\u00f3nomos<\/li>\n\n\n\n<li>Control de m\u00e9todos de trabajo<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Aprobar el Plan de Seguridad y Salud<\/strong> elaborado por el contratista<\/li>\n\n\n\n<li><strong>Organizar la coordinaci\u00f3n de actividades empresariales<\/strong> seg\u00fan el art\u00edculo 24 de la Ley 31\/1995<\/li>\n\n\n\n<li><strong>Coordinar el control de acceso<\/strong> a la obra<\/li>\n\n\n\n<li><strong>Adoptar medidas necesarias<\/strong> para que solo accedan personas autorizadas<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Gesti\u00f3n del Libro de Incidencias<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El coordinador debe:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Mantener siempre en obra<\/strong> el Libro de Incidencias<\/li>\n\n\n\n<li><strong>Realizar anotaciones<\/strong> sobre incumplimientos de las medidas preventivas<\/li>\n\n\n\n<li><strong>Enviar copia<\/strong> a la Inspecci\u00f3n de Trabajo en caso de anotaciones graves<\/li>\n\n\n\n<li><strong>Notificar las anotaciones<\/strong> al contratista afectado<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Requisitos_para_ser_Coordinador_de_Seguridad_y_Salud\"><\/span><strong>Requisitos para ser Coordinador de Seguridad y Salud<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Titulaci\u00f3n Acad\u00e9mica Obligatoria<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan la <strong><a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-1999-21567\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Ley de Ordenaci\u00f3n de la Edificaci\u00f3n (LOE)<\/a><\/strong>, las titulaciones habilitantes son:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2705 <strong>Arquitecto<\/strong> \u2705 <strong>Arquitecto T\u00e9cnico<\/strong> \u2705 <strong>Ingeniero<\/strong> \u2705 <strong>Ingeniero T\u00e9cnico<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Formaci\u00f3n en Prevenci\u00f3n de Riesgos Laborales<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de la titulaci\u00f3n, es <strong>fundamental<\/strong> contar con:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Formaci\u00f3n espec\u00edfica en PRL<\/strong> aplicable a obras de construcci\u00f3n<\/li>\n\n\n\n<li><strong>Curso de coordinador de seguridad y salud<\/strong> (recomendado m\u00ednimo 200 horas)<\/li>\n\n\n\n<li><strong>Conocimiento actualizado<\/strong> de la normativa vigente<\/li>\n\n\n\n<li><strong>Experiencia pr\u00e1ctica<\/strong> en obras de construcci\u00f3n<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Competencias y Habilidades Necesarias<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Un buen coordinador debe poseer:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Capacidad de liderazgo<\/strong> y comunicaci\u00f3n efectiva<\/li>\n\n\n\n<li><strong>Habilidades de gesti\u00f3n<\/strong> y organizaci\u00f3n<\/li>\n\n\n\n<li><strong>Conocimiento t\u00e9cnico<\/strong> de procesos constructivos<\/li>\n\n\n\n<li><strong>Capacidad de resoluci\u00f3n<\/strong> de conflictos<\/li>\n\n\n\n<li><strong>Visi\u00f3n preventiva<\/strong> y proactiva<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFQuien_Designa_al_Coordinador_de_Seguridad_y_Salud\"><\/span><strong>\u00bfQui\u00e9n Designa al Coordinador de Seguridad y Salud?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La designaci\u00f3n del coordinador es <strong>responsabilidad exclusiva del promotor<\/strong> de la obra. Esta obligaci\u00f3n:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>No puede delegarse<\/strong> en el contratista<\/li>\n\n\n\n<li><strong>No puede transferirse<\/strong> a terceros<\/li>\n\n\n\n<li>Debe realizarse <strong>antes del inicio de los trabajos<\/strong><\/li>\n\n\n\n<li>Puede recaer en la <strong>misma persona<\/strong> para ambas fases (proyecto y ejecuci\u00f3n)<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Responsabilidades del Promotor<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El promotor puede enfrentarse a <strong>sanciones graves<\/strong> si:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>No designa coordinador cuando es obligatorio<\/li>\n\n\n\n<li>El coordinador no cumple con sus funciones<\/li>\n\n\n\n<li>No se garantiza la presencia del coordinador en obra<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Documentacion_y_Registros_Obligatorios\"><\/span><strong>Documentaci\u00f3n y Registros Obligatorios<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El coordinador debe gestionar y mantener actualizada la siguiente documentaci\u00f3n:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Documentaci\u00f3n Principal<\/strong><\/h3>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Acta de nombramiento<\/strong> del Coordinador<\/li>\n\n\n\n<li><strong>Informe favorable<\/strong> del Plan de Seguridad y Salud<\/li>\n\n\n\n<li><strong>Libro de Incidencias<\/strong><\/li>\n\n\n\n<li><strong>Actas de reuniones<\/strong> de coordinaci\u00f3n<\/li>\n\n\n\n<li><strong>Registros de inspecciones<\/strong> realizadas<\/li>\n\n\n\n<li><strong>Comunicaciones<\/strong> con contratistas y subcontratistas<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Para Obras sin Proyecto<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Documento de Gesti\u00f3n Preventiva<\/strong> de la obra<\/li>\n\n\n\n<li><strong>Informe de supervisi\u00f3n<\/strong> del documento<\/li>\n\n\n\n<li><strong>Registros de seguimiento<\/strong> espec\u00edficos<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Diferencias_entre_Coordinador_en_Fase_de_Proyecto_y_Ejecucion\"><\/span><strong>Diferencias entre Coordinador en Fase de Proyecto y Ejecuci\u00f3n<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>Aspecto<\/strong><\/td><td><strong>Fase de Proyecto<\/strong><\/td><td><strong>Fase de Ejecuci\u00f3n<\/strong><\/td><\/tr><tr><td><strong>Momento de actuaci\u00f3n<\/strong><\/td><td>Durante elaboraci\u00f3n del proyecto<\/td><td>Durante la ejecuci\u00f3n de obra<\/td><\/tr><tr><td><strong>Integraci\u00f3n<\/strong><\/td><td>Equipo de proyectistas<\/td><td>Direcci\u00f3n Facultativa<\/td><\/tr><tr><td><strong>Funci\u00f3n principal<\/strong><\/td><td>Integrar prevenci\u00f3n en dise\u00f1o<\/td><td>Coordinar aplicaci\u00f3n del PSS<\/td><\/tr><tr><td><strong>Documento clave<\/strong><\/td><td>Estudio de Seguridad y Salud<\/td><td>Plan de Seguridad y Salud<\/td><\/tr><tr><td><strong>Presencia en obra<\/strong><\/td><td>No requerida<\/td><td>Obligatoria<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Preguntas_Frecuentes_sobre_el_Coordinador_de_Seguridad_y_Salud\"><\/span><strong>Preguntas Frecuentes sobre el Coordinador de Seguridad y Salud<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<div class=\"schema-faq wp-block-yoast-faq-block\"><div class=\"schema-faq-section\" id=\"faq-question-1777367160901\"><strong class=\"schema-faq-question\"><strong>\u00bfPuede el director de obra ser coordinador de seguridad y salud?<\/strong><\/strong> <p class=\"schema-faq-answer\"><strong>S\u00ed<\/strong>, siempre que:<br>-Cumpla con los requisitos de titulaci\u00f3n<br>-Solo intervenga una empresa o aut\u00f3nomo (sin subcontrataci\u00f3n)<br>-Tenga la formaci\u00f3n preventiva necesaria<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1777367181229\"><strong class=\"schema-faq-question\"><strong>\u00bfEs obligatorio un coordinador en obras sin proyecto?<\/strong><\/strong> <p class=\"schema-faq-answer\"><strong>S\u00ed<\/strong>, la obligaci\u00f3n <strong>no depende<\/strong> de la existencia de proyecto, sino de que intervengan m\u00e1s de una empresa o aut\u00f3nomo.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1777367208789\"><strong class=\"schema-faq-question\"><strong>\u00bfQu\u00e9 pasa si no se designa coordinador cuando es obligatorio?<\/strong><\/strong> <p class=\"schema-faq-answer\">El promotor se expone a:<br><strong>-Sanciones administrativas<\/strong> graves<br><strong>-Responsabilidades civiles<\/strong> por da\u00f1os<br><strong>-Responsabilidades penales<\/strong> en caso de accidente grave<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1777367290501\"><strong class=\"schema-faq-question\"><strong>\u00bfCu\u00e1nto cobra un coordinador de seguridad y salud?<\/strong><\/strong> <p class=\"schema-faq-answer\">Los honorarios var\u00edan seg\u00fan:<br>-Tipo y complejidad de la obra<br>-Duraci\u00f3n de los trabajos<br>-Experiencia del profesional<br>-Ubicaci\u00f3n geogr\u00e1fica<br>El rango habitual oscila entre <strong>1.500\u20ac y 4.000\u20ac mensuales<\/strong> para dedicaci\u00f3n completa.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1777367322812\"><strong class=\"schema-faq-question\"><strong>\u00bfPuede haber varios coordinadores en una misma obra?<\/strong><\/strong> <p class=\"schema-faq-answer\"><strong>No<\/strong>, solo puede haber:<br>-Un coordinador en fase de proyecto<br>-Un coordinador en fase de ejecuci\u00f3n<br>-Ambos cargos pueden recaer en la misma persona<\/p> <\/div> <\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Importancia_del_Coordinador_en_la_Prevencion_de_Accidentes\"><\/span><strong>Importancia del Coordinador en la Prevenci\u00f3n de Accidentes<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La presencia del <strong>coordinador de seguridad y salud<\/strong> ha demostrado ser <strong>fundamental<\/strong> para:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Reducci\u00f3n de la Siniestralidad<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Disminuci\u00f3n del 35%<\/strong> en accidentes graves<\/li>\n\n\n\n<li><strong>Reducci\u00f3n del 40%<\/strong> en incidentes por falta de coordinaci\u00f3n<\/li>\n\n\n\n<li><strong>Mejora del 45%<\/strong> en el cumplimiento normativo<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Beneficios para la Obra<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u2705 <strong>Mayor organizaci\u00f3n<\/strong> y control de riesgos \u2705 <strong>Mejor coordinaci\u00f3n<\/strong> entre empresas \u2705 <strong>Reducci\u00f3n de costes<\/strong> por accidentes \u2705 <strong>Cumplimiento legal<\/strong> garantizado \u2705 <strong>Ambiente de trabajo<\/strong> m\u00e1s seguro<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Herramientas_y_Software_para_Coordinadores\"><\/span><strong>Herramientas y Software para Coordinadores<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los coordinadores modernos utilizan:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Software Especializado<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Plataformas de coordinaci\u00f3n CAE<\/strong><\/li>\n\n\n\n<li><strong>Aplicaciones de gesti\u00f3n documental<\/strong><\/li>\n\n\n\n<li><strong>Software de planificaci\u00f3n preventiva<\/strong><\/li>\n\n\n\n<li><strong>Herramientas BIM<\/strong> para integraci\u00f3n preventiva<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Documentaci\u00f3n Digital<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Libro de Incidencias digital<\/strong><\/li>\n\n\n\n<li><strong>Actas electr\u00f3nicas<\/strong><\/li>\n\n\n\n<li><strong>Registro fotogr\u00e1fico<\/strong> de inspecciones<\/li>\n\n\n\n<li><strong>Comunicaciones trazables<\/strong><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Formacion_Continua_y_Actualizacion\"><\/span><strong>Formaci\u00f3n Continua y Actualizaci\u00f3n<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para mantener la competencia profesional, es esencial:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Formaci\u00f3n Recomendada<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>M\u00e1ster en PRL<\/strong> especialidad construcci\u00f3n<\/li>\n\n\n\n<li><strong>Cursos de actualizaci\u00f3n<\/strong> normativa<\/li>\n\n\n\n<li><strong>Certificaciones ISO 45001<\/strong><\/li>\n\n\n\n<li><strong>Formaci\u00f3n en nuevas tecnolog\u00edas<\/strong> (BIM, drones, etc.)<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Networking Profesional<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Colegios profesionales<\/li>\n\n\n\n<li>Asociaciones de coordinadores<\/li>\n\n\n\n<li>Jornadas t\u00e9cnicas<\/li>\n\n\n\n<li>Congresos de prevenci\u00f3n<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Conclusiones\"><\/span><strong>Conclusiones<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El <strong>coordinador de seguridad y salud<\/strong> es una figura <strong>imprescindible<\/strong> en el sector de la construcci\u00f3n espa\u00f1ol. Su labor va m\u00e1s all\u00e1 del mero cumplimiento normativo, siendo un <strong>garante de la seguridad<\/strong> de todos los trabajadores en obra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para ejercer con \u00e9xito como <strong>coordinador seguridad y salud<\/strong>, es necesario:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Formaci\u00f3n t\u00e9cnica s\u00f3lida<\/strong> y actualizada<\/li>\n\n\n\n<li><strong>Conocimiento profundo<\/strong> de la normativa<\/li>\n\n\n\n<li><strong>Experiencia pr\u00e1ctica<\/strong> en obras<\/li>\n\n\n\n<li><strong>Compromiso real<\/strong> con la prevenci\u00f3n<\/li>\n\n\n\n<li><strong>Habilidades de gesti\u00f3n<\/strong> y comunicaci\u00f3n<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">La <strong>coordinaci\u00f3n de seguridad y salud<\/strong> no es solo una obligaci\u00f3n legal, sino una <strong>inversi\u00f3n en vidas humanas<\/strong> y en la eficiencia de los proyectos constructivos. Un buen coordinador marca la diferencia entre una obra segura y exitosa, y una obra con riesgos innecesarios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si est\u00e1s pensando en contratar un coordinador o formarte como tal, recuerda que la seguridad no es un gasto, sino la mejor inversi\u00f3n para garantizar el \u00e9xito de cualquier proyecto de construcci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El coordinador de seguridad y salud es una figura esencial en el sector de la construcci\u00f3n en Espa\u00f1a. Si est\u00e1s buscando informaci\u00f3n completa sobre esta profesi\u00f3n, sus funciones, requisitos y obligaciones, has llegado al lugar correcto. En esta gu\u00eda exhaustiva, te explicaremos todo lo que necesitas saber sobre la coordinaci\u00f3n de seguridad y salud en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4121,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":"","tve_updated_post":"","tve_custom_css":"","tve_user_custom_css":"","tve_globals":{},"tcb2_ready":0,"tcb_editor_enabled":0,"tve_landing_page":"","_tve_header":"","_tve_footer":""},"categories":[1,31],"tags":[],"class_list":["post-4118","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coordinacion-actividades-empresariales","category-prevencion-de-riesgos-laborales","post-wrapper","thrv_wrapper"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Coordinador Seguridad y Salud \u25b7 Funciones y Requisitos<\/title>\n<meta name=\"description\" content=\"\u2705 Descubre TODO sobre el coordinador de seguridad y salud: funciones, requisitos, cu\u00e1ndo es obligatorio y documentaci\u00f3n necesaria.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coordinador Seguridad y Salud \u25b7 Funciones y Requisitos\" \/>\n<meta property=\"og:description\" content=\"\u2705 Descubre TODO sobre el coordinador de seguridad y salud: funciones, requisitos, cu\u00e1ndo es obligatorio y documentaci\u00f3n necesaria.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/\" \/>\n<meta property=\"og:site_name\" content=\"Twind - Plataforma de Coordinaci\u00f3n de Actividades Empresariales\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-03T14:37:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-26T09:56:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/twind.io\/es\/wp-content\/uploads\/2025\/06\/coordinador-seguridad-salud-obra-construccion.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"666\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Twind Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Twind Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/coordinador-seguridad-salud\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/coordinador-seguridad-salud\\\/\"},\"author\":{\"name\":\"Twind Team\",\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/#\\\/schema\\\/person\\\/4f69058786bd1debb9748aaeb897a69c\"},\"headline\":\"Coordinador de Seguridad y Salud: Todo lo que Necesitas Saber\",\"datePublished\":\"2025-06-03T14:37:15+00:00\",\"dateModified\":\"2026-05-26T09:56:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/coordinador-seguridad-salud\\\/\"},\"wordCount\":1475,\"image\":{\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/coordinador-seguridad-salud\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/twind.io\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/coordinador-seguridad-salud-obra-construccion.webp\",\"articleSection\":[\"Coordinaci\u00f3n de Actividades Empresariales\",\"Prevenci\u00f3n de Riesgos Laborales\"],\"inLanguage\":\"es\"},{\"@type\":[\"WebPage\",\"FAQPage\"],\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/coordinador-seguridad-salud\\\/\",\"url\":\"https:\\\/\\\/twind.io\\\/es\\\/coordinador-seguridad-salud\\\/\",\"name\":\"Coordinador Seguridad y Salud \u25b7 Funciones y Requisitos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/coordinador-seguridad-salud\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/coordinador-seguridad-salud\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/twind.io\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/coordinador-seguridad-salud-obra-construccion.webp\",\"datePublished\":\"2025-06-03T14:37:15+00:00\",\"dateModified\":\"2026-05-26T09:56:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/#\\\/schema\\\/person\\\/4f69058786bd1debb9748aaeb897a69c\"},\"description\":\"\u2705 Descubre TODO sobre el coordinador de seguridad y salud: funciones, requisitos, cu\u00e1ndo es obligatorio y documentaci\u00f3n necesaria.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/coordinador-seguridad-salud\\\/#breadcrumb\"},\"mainEntity\":[{\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/coordinador-seguridad-salud\\\/#faq-question-1777367160901\"},{\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/coordinador-seguridad-salud\\\/#faq-question-1777367181229\"},{\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/coordinador-seguridad-salud\\\/#faq-question-1777367208789\"},{\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/coordinador-seguridad-salud\\\/#faq-question-1777367290501\"},{\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/coordinador-seguridad-salud\\\/#faq-question-1777367322812\"}],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/twind.io\\\/es\\\/coordinador-seguridad-salud\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/coordinador-seguridad-salud\\\/#primaryimage\",\"url\":\"https:\\\/\\\/twind.io\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/coordinador-seguridad-salud-obra-construccion.webp\",\"contentUrl\":\"https:\\\/\\\/twind.io\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/coordinador-seguridad-salud-obra-construccion.webp\",\"width\":1000,\"height\":666,\"caption\":\"Coordinador de seguridad y salud revisando plan de prevenci\u00f3n en construcci\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/coordinador-seguridad-salud\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/twind.io\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coordinador de Seguridad y Salud: Todo lo que Necesitas Saber\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/twind.io\\\/es\\\/\",\"name\":\"Twind - Plataforma de Coordinaci\u00f3n de Actividades Empresariales\",\"description\":\"Coordina los procesos de gesti\u00f3n documental y control de contratistas y proveedores, respetando la normativa en materia de Seguridad y Salud en el Trabajo.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/twind.io\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/#\\\/schema\\\/person\\\/4f69058786bd1debb9748aaeb897a69c\",\"name\":\"Twind Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g\",\"caption\":\"Twind Team\"},\"description\":\"Comunicaci\u00f3n y contenidos\",\"sameAs\":[\"https:\\\/\\\/twind.io\\\/es\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/twind-io\\\/\"],\"url\":\"https:\\\/\\\/twind.io\\\/es\\\/author\\\/rrios_6eq9khcx\\\/\"},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/coordinador-seguridad-salud\\\/#faq-question-1777367160901\",\"position\":1,\"url\":\"https:\\\/\\\/twind.io\\\/es\\\/coordinador-seguridad-salud\\\/#faq-question-1777367160901\",\"name\":\"\u00bfPuede el director de obra ser coordinador de seguridad y salud?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<strong>S\u00ed<\\\/strong>, siempre que:<br>-Cumpla con los requisitos de titulaci\u00f3n<br>-Solo intervenga una empresa o aut\u00f3nomo (sin subcontrataci\u00f3n)<br>-Tenga la formaci\u00f3n preventiva necesaria\",\"inLanguage\":\"es\"},\"inLanguage\":\"es\"},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/coordinador-seguridad-salud\\\/#faq-question-1777367181229\",\"position\":2,\"url\":\"https:\\\/\\\/twind.io\\\/es\\\/coordinador-seguridad-salud\\\/#faq-question-1777367181229\",\"name\":\"\u00bfEs obligatorio un coordinador en obras sin proyecto?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<strong>S\u00ed<\\\/strong>, la obligaci\u00f3n <strong>no depende<\\\/strong> de la existencia de proyecto, sino de que intervengan m\u00e1s de una empresa o aut\u00f3nomo.\",\"inLanguage\":\"es\"},\"inLanguage\":\"es\"},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/coordinador-seguridad-salud\\\/#faq-question-1777367208789\",\"position\":3,\"url\":\"https:\\\/\\\/twind.io\\\/es\\\/coordinador-seguridad-salud\\\/#faq-question-1777367208789\",\"name\":\"\u00bfQu\u00e9 pasa si no se designa coordinador cuando es obligatorio?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"El promotor se expone a:<br><strong>-Sanciones administrativas<\\\/strong> graves<br><strong>-Responsabilidades civiles<\\\/strong> por da\u00f1os<br><strong>-Responsabilidades penales<\\\/strong> en caso de accidente grave\",\"inLanguage\":\"es\"},\"inLanguage\":\"es\"},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/coordinador-seguridad-salud\\\/#faq-question-1777367290501\",\"position\":4,\"url\":\"https:\\\/\\\/twind.io\\\/es\\\/coordinador-seguridad-salud\\\/#faq-question-1777367290501\",\"name\":\"\u00bfCu\u00e1nto cobra un coordinador de seguridad y salud?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Los honorarios var\u00edan seg\u00fan:<br>-Tipo y complejidad de la obra<br>-Duraci\u00f3n de los trabajos<br>-Experiencia del profesional<br>-Ubicaci\u00f3n geogr\u00e1fica<br>El rango habitual oscila entre <strong>1.500\u20ac y 4.000\u20ac mensuales<\\\/strong> para dedicaci\u00f3n completa.\",\"inLanguage\":\"es\"},\"inLanguage\":\"es\"},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/twind.io\\\/es\\\/coordinador-seguridad-salud\\\/#faq-question-1777367322812\",\"position\":5,\"url\":\"https:\\\/\\\/twind.io\\\/es\\\/coordinador-seguridad-salud\\\/#faq-question-1777367322812\",\"name\":\"\u00bfPuede haber varios coordinadores en una misma obra?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<strong>No<\\\/strong>, solo puede haber:<br>-Un coordinador en fase de proyecto<br>-Un coordinador en fase de ejecuci\u00f3n<br>-Ambos cargos pueden recaer en la misma persona\",\"inLanguage\":\"es\"},\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coordinador Seguridad y Salud \u25b7 Funciones y Requisitos","description":"\u2705 Descubre TODO sobre el coordinador de seguridad y salud: funciones, requisitos, cu\u00e1ndo es obligatorio y documentaci\u00f3n necesaria.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/","og_locale":"es_ES","og_type":"article","og_title":"Coordinador Seguridad y Salud \u25b7 Funciones y Requisitos","og_description":"\u2705 Descubre TODO sobre el coordinador de seguridad y salud: funciones, requisitos, cu\u00e1ndo es obligatorio y documentaci\u00f3n necesaria.","og_url":"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/","og_site_name":"Twind - Plataforma de Coordinaci\u00f3n de Actividades Empresariales","article_published_time":"2025-06-03T14:37:15+00:00","article_modified_time":"2026-05-26T09:56:29+00:00","og_image":[{"width":1000,"height":666,"url":"https:\/\/twind.io\/es\/wp-content\/uploads\/2025\/06\/coordinador-seguridad-salud-obra-construccion.webp","type":"image\/webp"}],"author":"Twind Team","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Twind Team","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#article","isPartOf":{"@id":"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/"},"author":{"name":"Twind Team","@id":"https:\/\/twind.io\/es\/#\/schema\/person\/4f69058786bd1debb9748aaeb897a69c"},"headline":"Coordinador de Seguridad y Salud: Todo lo que Necesitas Saber","datePublished":"2025-06-03T14:37:15+00:00","dateModified":"2026-05-26T09:56:29+00:00","mainEntityOfPage":{"@id":"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/"},"wordCount":1475,"image":{"@id":"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#primaryimage"},"thumbnailUrl":"https:\/\/twind.io\/es\/wp-content\/uploads\/2025\/06\/coordinador-seguridad-salud-obra-construccion.webp","articleSection":["Coordinaci\u00f3n de Actividades Empresariales","Prevenci\u00f3n de Riesgos Laborales"],"inLanguage":"es"},{"@type":["WebPage","FAQPage"],"@id":"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/","url":"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/","name":"Coordinador Seguridad y Salud \u25b7 Funciones y Requisitos","isPartOf":{"@id":"https:\/\/twind.io\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#primaryimage"},"image":{"@id":"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#primaryimage"},"thumbnailUrl":"https:\/\/twind.io\/es\/wp-content\/uploads\/2025\/06\/coordinador-seguridad-salud-obra-construccion.webp","datePublished":"2025-06-03T14:37:15+00:00","dateModified":"2026-05-26T09:56:29+00:00","author":{"@id":"https:\/\/twind.io\/es\/#\/schema\/person\/4f69058786bd1debb9748aaeb897a69c"},"description":"\u2705 Descubre TODO sobre el coordinador de seguridad y salud: funciones, requisitos, cu\u00e1ndo es obligatorio y documentaci\u00f3n necesaria.","breadcrumb":{"@id":"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#breadcrumb"},"mainEntity":[{"@id":"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#faq-question-1777367160901"},{"@id":"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#faq-question-1777367181229"},{"@id":"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#faq-question-1777367208789"},{"@id":"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#faq-question-1777367290501"},{"@id":"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#faq-question-1777367322812"}],"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/twind.io\/es\/coordinador-seguridad-salud\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#primaryimage","url":"https:\/\/twind.io\/es\/wp-content\/uploads\/2025\/06\/coordinador-seguridad-salud-obra-construccion.webp","contentUrl":"https:\/\/twind.io\/es\/wp-content\/uploads\/2025\/06\/coordinador-seguridad-salud-obra-construccion.webp","width":1000,"height":666,"caption":"Coordinador de seguridad y salud revisando plan de prevenci\u00f3n en construcci\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/twind.io\/es\/"},{"@type":"ListItem","position":2,"name":"Coordinador de Seguridad y Salud: Todo lo que Necesitas Saber"}]},{"@type":"WebSite","@id":"https:\/\/twind.io\/es\/#website","url":"https:\/\/twind.io\/es\/","name":"Twind - Plataforma de Coordinaci\u00f3n de Actividades Empresariales","description":"Coordina los procesos de gesti\u00f3n documental y control de contratistas y proveedores, respetando la normativa en materia de Seguridad y Salud en el Trabajo.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/twind.io\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/twind.io\/es\/#\/schema\/person\/4f69058786bd1debb9748aaeb897a69c","name":"Twind Team","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g","caption":"Twind Team"},"description":"Comunicaci\u00f3n y contenidos","sameAs":["https:\/\/twind.io\/es\/","https:\/\/www.linkedin.com\/showcase\/twind-io\/"],"url":"https:\/\/twind.io\/es\/author\/rrios_6eq9khcx\/"},{"@type":"Question","@id":"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#faq-question-1777367160901","position":1,"url":"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#faq-question-1777367160901","name":"\u00bfPuede el director de obra ser coordinador de seguridad y salud?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"<strong>S\u00ed<\/strong>, siempre que:<br>-Cumpla con los requisitos de titulaci\u00f3n<br>-Solo intervenga una empresa o aut\u00f3nomo (sin subcontrataci\u00f3n)<br>-Tenga la formaci\u00f3n preventiva necesaria","inLanguage":"es"},"inLanguage":"es"},{"@type":"Question","@id":"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#faq-question-1777367181229","position":2,"url":"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#faq-question-1777367181229","name":"\u00bfEs obligatorio un coordinador en obras sin proyecto?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"<strong>S\u00ed<\/strong>, la obligaci\u00f3n <strong>no depende<\/strong> de la existencia de proyecto, sino de que intervengan m\u00e1s de una empresa o aut\u00f3nomo.","inLanguage":"es"},"inLanguage":"es"},{"@type":"Question","@id":"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#faq-question-1777367208789","position":3,"url":"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#faq-question-1777367208789","name":"\u00bfQu\u00e9 pasa si no se designa coordinador cuando es obligatorio?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"El promotor se expone a:<br><strong>-Sanciones administrativas<\/strong> graves<br><strong>-Responsabilidades civiles<\/strong> por da\u00f1os<br><strong>-Responsabilidades penales<\/strong> en caso de accidente grave","inLanguage":"es"},"inLanguage":"es"},{"@type":"Question","@id":"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#faq-question-1777367290501","position":4,"url":"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#faq-question-1777367290501","name":"\u00bfCu\u00e1nto cobra un coordinador de seguridad y salud?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Los honorarios var\u00edan seg\u00fan:<br>-Tipo y complejidad de la obra<br>-Duraci\u00f3n de los trabajos<br>-Experiencia del profesional<br>-Ubicaci\u00f3n geogr\u00e1fica<br>El rango habitual oscila entre <strong>1.500\u20ac y 4.000\u20ac mensuales<\/strong> para dedicaci\u00f3n completa.","inLanguage":"es"},"inLanguage":"es"},{"@type":"Question","@id":"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#faq-question-1777367322812","position":5,"url":"https:\/\/twind.io\/es\/coordinador-seguridad-salud\/#faq-question-1777367322812","name":"\u00bfPuede haber varios coordinadores en una misma obra?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"<strong>No<\/strong>, solo puede haber:<br>-Un coordinador en fase de proyecto<br>-Un coordinador en fase de ejecuci\u00f3n<br>-Ambos cargos pueden recaer en la misma persona","inLanguage":"es"},"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/twind.io\/es\/wp-json\/wp\/v2\/posts\/4118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/twind.io\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/twind.io\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/twind.io\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/twind.io\/es\/wp-json\/wp\/v2\/comments?post=4118"}],"version-history":[{"count":3,"href":"https:\/\/twind.io\/es\/wp-json\/wp\/v2\/posts\/4118\/revisions"}],"predecessor-version":[{"id":38815,"href":"https:\/\/twind.io\/es\/wp-json\/wp\/v2\/posts\/4118\/revisions\/38815"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/twind.io\/es\/wp-json\/wp\/v2\/media\/4121"}],"wp:attachment":[{"href":"https:\/\/twind.io\/es\/wp-json\/wp\/v2\/media?parent=4118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/twind.io\/es\/wp-json\/wp\/v2\/categories?post=4118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/twind.io\/es\/wp-json\/wp\/v2\/tags?post=4118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}