{"id":2132,"date":"2024-07-01T12:37:15","date_gmt":"2024-07-01T12:37:15","guid":{"rendered":"https:\/\/twind.io\/mx\/?p=2132"},"modified":"2024-07-31T11:38:47","modified_gmt":"2024-07-31T11:38:47","slug":"6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas","status":"publish","type":"post","link":"https:\/\/twind.io\/mx\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\/","title":{"rendered":"6 razones para eliminar las hojas de c\u00e1lculo de tu gesti\u00f3n de contratistas\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Muchos departamentos de Seguridad todav\u00eda se resisten a automatizar la gesti\u00f3n de contratistas. Y contin\u00faan invirtiendo largas jornadas de trabajo intentando poner orden en los Excel, hojas de c\u00e1lculo, correos electr\u00f3nicos y carpetas del servidor\u2026 sin \u00e9xito. Asumiendo as\u00ed, grandes riesgos en la gesti\u00f3n de contratistas.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Tabla de Contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #6b6b6b;color:#6b6b6b\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #6b6b6b;color:#6b6b6b\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/twind.io\/mx\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\/#%C2%BFCuales_son_las_desventajas_de_utilizar_las_hojas_de_calculo_para_la_gestion_de_contratistas\" >\u00bfCu\u00e1les son las desventajas de utilizar las hojas de c\u00e1lculo para la gesti\u00f3n de contratistas?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/twind.io\/mx\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\/#Las_hojas_de_calculo_conducen_a_errores\" >Las hojas de c\u00e1lculo conducen a errores&nbsp;<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/twind.io\/mx\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\/#La_integridad_de_los_datos_de_la_gestion_de_contratistas_no_es_fiable\" >La integridad de los datos de la gesti\u00f3n de contratistas no es fiable&nbsp;<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/twind.io\/mx\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\/#El_trabajo_manual_es_abundante_y_consume_tiempo\" >El trabajo manual es abundante&nbsp;y consume tiempo&nbsp;<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/twind.io\/mx\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\/#Los_datos_de_los_contratistas_estan_aislados_y_no_hay_colaboracion\" >Los datos de los contratistas est\u00e1n aislados y no hay colaboraci\u00f3n&nbsp;&nbsp;<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/twind.io\/mx\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\/#Las_hojas_de_calculo_imposibilitan_escalar_la_gestion_de_contratistas\" >Las hojas de c\u00e1lculo imposibilitan escalar la gesti\u00f3n de contratistas&nbsp;<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/twind.io\/mx\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\/#El_analisis_de_riesgos_es_casi_imposible\" >El an\u00e1lisis de riesgos es casi imposible&nbsp;<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/twind.io\/mx\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\/#%C2%BFPor_que_es_necesario_automatizar_la_gestion_de_contratistas\" >\u00bfPor qu\u00e9 es necesario automatizar la gesti\u00f3n de contratistas?<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/twind.io\/mx\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\/#Contactanos_para_obtener_mas_informacion_sobre_como_eliminar_las_hojas_de_calculo_y_digitalizar_tu_sistema_de_gestion_de_contratistas\" >Cont\u00e1ctanos para obtener m\u00e1s informaci\u00f3n sobre&nbsp;c\u00f3mo eliminar las hojas de c\u00e1lculo y digitalizar tu sistema de gesti\u00f3n de contratistas.&nbsp;<\/a><\/li><\/ul><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFCuales_son_las_desventajas_de_utilizar_las_hojas_de_calculo_para_la_gestion_de_contratistas\"><\/span><strong>\u00bfCu\u00e1les son las desventajas de utilizar las hojas de c\u00e1lculo para la gesti\u00f3n de contratistas?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Desafortunadamente, continuar apostando por una gesti\u00f3n manual y en Excel de tus contratistas solo tiene desventajas:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Las_hojas_de_calculo_conducen_a_errores\"><\/span><strong>Las hojas de c\u00e1lculo conducen a errores<\/strong>&nbsp;<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Los Excel, las distintas versiones obsoletas, la falta de control y los m\u00faltiples errores son una constante en la gesti\u00f3n manual de los contratistas.&nbsp;&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Quiz\u00e1s el documento que buscas se encuentra en una carpeta del servidor a la que no tienes acceso, o est\u00e1 en el servidor de toda la empresa y cualquier usuario puede abrir un archivo de hoja de c\u00e1lculo y realizar cambios, introduciendo datos poco fiables o err\u00f3neos.&nbsp;&nbsp;<\/li>\n\n\n\n<li>Sin supervisi\u00f3n, los errores son una constante en las hojas de c\u00e1lculo que utilizas para gestionar a tus contratistas. Poniendo en riesgo a todos los trabajadores que acceden a tu centro de trabajo y asumiendo potenciales sanciones y responsabilidades, por el incumplimiento de la normativa en PRL.&nbsp;&nbsp;<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"La_integridad_de_los_datos_de_la_gestion_de_contratistas_no_es_fiable\"><\/span><strong>La integridad de los datos de la gesti\u00f3n de contratistas no es fiable<\/strong>&nbsp;<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando los datos son precisos, puedes tomar decisiones para proteger a todos los trabajadores que acceden a tu centro de trabajo y proteger as\u00ed a tu organizaci\u00f3n de los riesgos laborales y reputacionales y garantizar que cumples con toda la normativa.&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sin embargo, en las hojas de c\u00e1lculo, donde las f\u00f3rmulas, fechas y los enlaces, las evidencias se eliminan o modifican f\u00e1cilmente mediante acciones comunes como cortar y pegar, no garantizan la precisi\u00f3n de los datos.&nbsp;&nbsp;<\/li>\n\n\n\n<li>Adem\u00e1s, el sistema no te permite garantizar la vigencia de los documentos de trabajadores, equipos y maquinaria que solicitas a tus contratistas, de forma autom\u00e1tica.&nbsp;&nbsp;<\/li>\n\n\n\n<li>Ni tampoco puedes reportar toda la trazabilidad de las versiones, comentarios, cambios que han sufrido los documentos de PRL.&nbsp;&nbsp;<\/li>\n\n\n\n<li>Cuando se trabaja con Excel para gesti\u00f3n de contratistas, no se cuenta con notificaciones y avisos autom\u00e1ticos, con lo que se te escapan incumplimientos y caducidades.&nbsp;&nbsp;<\/li>\n\n\n\n<li>Y, por \u00faltimo, no puedes garantizar la custodia legal de la documentaci\u00f3n. Especialmente necesaria en caso de inspecci\u00f3n, accidente de trabajo o auditor\u00eda.&nbsp;&nbsp;<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"El_trabajo_manual_es_abundante_y_consume_tiempo\"><\/span><strong>El trabajo manual es abundante&nbsp;y consume tiempo<\/strong>&nbsp;<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Gestionar los contratistas con hojas de c\u00e1lculo, hace que los equipos de Prevenci\u00f3n de Riesgos Laborales, Administraci\u00f3n, Mantenimiento y Compras&nbsp;<strong>dediquen mucho tiempo<\/strong>.&nbsp;&nbsp;<\/li>\n\n\n\n<li>Adem\u00e1s, habitualmente hay&nbsp;<strong>problemas de control de versiones o una hoja de c\u00e1lculo desactualizada<\/strong>&nbsp;que no se actualiza peri\u00f3dicamente.&nbsp;&nbsp;<\/li>\n\n\n\n<li>Cuando&nbsp;<strong>solo una persona realiza la gesti\u00f3n de contratistas con Excel<\/strong>, es posible que ni los contratistas, ni sus compa\u00f1eros entiendan el proceso ni los formatos de manera intuitiva o que tengan acceso a los archivos.&nbsp;&nbsp;<\/li>\n\n\n\n<li>Pero el mayor reto surge cuando el<strong>&nbsp;trabajo de actualizar los Excel<\/strong>&nbsp;se vuelve una tarea ardua, y lleva m\u00e1s tiempo gestionar todos los Excel que establecer medidas preventivas, evaluar riesgos, homologar a proveedores, realizar formaciones en prevenci\u00f3n, llevar a cabo inspecciones de campo\u2026&nbsp;<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Los_datos_de_los_contratistas_estan_aislados_y_no_hay_colaboracion\"><\/span><strong>Los datos de los contratistas est\u00e1n aislados y no hay colaboraci\u00f3n&nbsp;<\/strong>&nbsp;<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En aquellas empresas en las que la gesti\u00f3n de contratistas se realiza con hojas de c\u00e1lculo, a menudo el equipo de Seguridad de forma independiente, administrando sus propios datos y gestionando todo el flujo de trabajo. Asumiendo toda la responsabilidad y carga de trabajo.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, cuando se&nbsp;<strong>automatiza la gesti\u00f3n de contratistas<\/strong>&nbsp;se fomenta la&nbsp;<strong>colaboraci\u00f3n entre departamentos<\/strong>&nbsp;y con los contratistas.&nbsp;&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Las_hojas_de_calculo_imposibilitan_escalar_la_gestion_de_contratistas\"><\/span><strong>Las hojas de c\u00e1lculo imposibilitan escalar la gesti\u00f3n de contratistas<\/strong>&nbsp;<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Est\u00e1 bien, los Excel son una buena herramienta para proyectos peque\u00f1os. Pero cuando tu organizaci\u00f3n necesita gestionar un volumen mayor de contratistas, la gesti\u00f3n se vuelve inasumible.&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Los&nbsp;<strong>proyectos m\u00e1s grandes<\/strong>&nbsp;(paradas de mantenimiento, contratistas habituales, empresas de transporte y facility management, etc.) significan asumir m\u00e1s contratistas, m\u00e1s equipos de trabajo y trabadores externos a gestionar, asumir m\u00e1s riesgos\u2026 y sin poder llevar un control al d\u00eda.&nbsp;&nbsp;<\/li>\n\n\n\n<li>A diferencia de un&nbsp;<strong>Software para la Gesti\u00f3n de Contratistas<\/strong>, las hojas de c\u00e1lculo tampoco integran en tiempo real informaci\u00f3n y datos como permisos de trabajo, contratos y documentaci\u00f3n de cumplimiento, por lo que esas piezas son m\u00e1s dif\u00edciles de monitorear.&nbsp;&nbsp;<\/li>\n\n\n\n<li>Por lo que no tienes la certeza de que todos los trabajadores, contratistas y equipos de trabajo que acceden a tus instalaciones cumplen con tus est\u00e1ndares de seguridad, evitando riesgos.&nbsp;&nbsp;<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"El_analisis_de_riesgos_es_casi_imposible\"><\/span><strong>El an\u00e1lisis de riesgos es casi imposible<\/strong>&nbsp;<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando necesitas extraer informes, indicadores y realizar an\u00e1lisis detallados con objeto de definir tu planificaci\u00f3n de actividades preventivas, o encontrar&nbsp;<em>gaps<\/em>&nbsp;y potenciales riesgos de tus contratistas, una hoja de c\u00e1lculo no es suficiente.&nbsp;&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Los Excel no solo son menos fiables cuando se gestionan vol\u00famenes de datos importantes, sino que debes pasar cada vez m\u00e1s tiempo con los datos y los reportes. Porque el Excel no te permite cotejar, analizar e informar de las m\u00e9tricas clave autom\u00e1ticamente.&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>A trav\u00e9s de las alertas del sistema automatizado, un\u00a0<strong>Software de Gesti\u00f3n de Contratistas como Twind<\/strong>\u00a0puede identificar y prevenir los fallos antes de que sucedan.\u00a0<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFPor_que_es_necesario_automatizar_la_gestion_de_contratistas\"><\/span><strong>\u00bfPor qu\u00e9 es necesario automatizar la gesti\u00f3n de contratistas?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A medida que se&nbsp;<strong>eliminan las tareas manuales<\/strong>&nbsp;y se&nbsp;<strong>mejora la colaboraci\u00f3n<\/strong>, la gesti\u00f3n de contratistas automatizada se convierte en un activo para tu organizaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Generas&nbsp;<strong>cultura preventiva, facilitando y agilizando la toma de decisiones<\/strong>&nbsp;para prevenir incidentes y accidentes de tus trabajadores y contratas.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Contactanos_para_obtener_mas_informacion_sobre_como_eliminar_las_hojas_de_calculo_y_digitalizar_tu_sistema_de_gestion_de_contratistas\"><\/span><strong>Cont\u00e1ctanos para obtener m\u00e1s informaci\u00f3n sobre&nbsp;c\u00f3mo eliminar las hojas de c\u00e1lculo y digitalizar tu sistema de gesti\u00f3n de contratistas.&nbsp;<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Muchos departamentos de Seguridad todav\u00eda se resisten a automatizar la gesti\u00f3n de contratistas. Y contin\u00faan invirtiendo largas jornadas de trabajo intentando poner orden en los Excel, hojas de c\u00e1lculo, correos electr\u00f3nicos y carpetas del servidor\u2026 sin \u00e9xito. Asumiendo as\u00ed, grandes riesgos en la gesti\u00f3n de contratistas. \u00bfCu\u00e1les son las desventajas de utilizar las hojas de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2133,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":"","tve_updated_post":"","tve_custom_css":"","tve_user_custom_css":"","tve_globals":{},"tcb2_ready":0,"tcb_editor_enabled":0,"tve_landing_page":"","_tve_header":"","_tve_footer":""},"categories":[20],"tags":[],"class_list":["post-2132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contratos-de-servicios-especializados","post-wrapper","thrv_wrapper"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>6 razones para eliminar las hojas de c\u00e1lculo de tu gesti\u00f3n de contratistas\u00a0 - Plataforma de Gesti\u00f3n de Contratistas y Proveedores<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"6 razones para eliminar las hojas de c\u00e1lculo de tu gesti\u00f3n de contratistas\u00a0 - Plataforma de Gesti\u00f3n de Contratistas y Proveedores\" \/>\n<meta property=\"og:description\" content=\"Muchos departamentos de Seguridad todav\u00eda se resisten a automatizar la gesti\u00f3n de contratistas. Y contin\u00faan invirtiendo largas jornadas de trabajo intentando poner orden en los Excel, hojas de c\u00e1lculo, correos electr\u00f3nicos y carpetas del servidor\u2026 sin \u00e9xito. Asumiendo as\u00ed, grandes riesgos en la gesti\u00f3n de contratistas. \u00bfCu\u00e1les son las desventajas de utilizar las hojas de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/twind.io\/mx\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\/\" \/>\n<meta property=\"og:site_name\" content=\"Plataforma de Gesti\u00f3n de Contratistas y Proveedores\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-01T12:37:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-31T11:38:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/twind.io\/mx\/wp-content\/uploads\/2024\/07\/eliminar-hojas-excel-gestion-contratistas-1024x576-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/twind.io\\\/mx\\\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/twind.io\\\/mx\\\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/twind.io\\\/mx\\\/#\\\/schema\\\/person\\\/6c97e4770a14bee4d5d19e5239e742eb\"},\"headline\":\"6 razones para eliminar las hojas de c\u00e1lculo de tu gesti\u00f3n de contratistas\u00a0\",\"datePublished\":\"2024-07-01T12:37:15+00:00\",\"dateModified\":\"2024-07-31T11:38:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/twind.io\\\/mx\\\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\\\/\"},\"wordCount\":1094,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/twind.io\\\/mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/twind.io\\\/mx\\\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/twind.io\\\/mx\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/eliminar-hojas-excel-gestion-contratistas-1024x576-1.jpg\",\"articleSection\":[\"Contratos de Servicios Especializados\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/twind.io\\\/mx\\\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/twind.io\\\/mx\\\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\\\/\",\"url\":\"https:\\\/\\\/twind.io\\\/mx\\\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\\\/\",\"name\":\"6 razones para eliminar las hojas de c\u00e1lculo de tu gesti\u00f3n de contratistas\u00a0 - Plataforma de Gesti\u00f3n de Contratistas y Proveedores\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/twind.io\\\/mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/twind.io\\\/mx\\\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/twind.io\\\/mx\\\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/twind.io\\\/mx\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/eliminar-hojas-excel-gestion-contratistas-1024x576-1.jpg\",\"datePublished\":\"2024-07-01T12:37:15+00:00\",\"dateModified\":\"2024-07-31T11:38:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/twind.io\\\/mx\\\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/twind.io\\\/mx\\\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/twind.io\\\/mx\\\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/twind.io\\\/mx\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/eliminar-hojas-excel-gestion-contratistas-1024x576-1.jpg\",\"contentUrl\":\"https:\\\/\\\/twind.io\\\/mx\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/eliminar-hojas-excel-gestion-contratistas-1024x576-1.jpg\",\"width\":1024,\"height\":576},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/twind.io\\\/mx\\\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/twind.io\\\/mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"6 razones para eliminar las hojas de c\u00e1lculo de tu gesti\u00f3n de contratistas\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/twind.io\\\/mx\\\/#website\",\"url\":\"https:\\\/\\\/twind.io\\\/mx\\\/\",\"name\":\"Plataforma de Gesti\u00f3n de Contratistas y Proveedores\",\"description\":\"Simplifica y automatiza la gesti\u00f3n de contratistas desde un solo lugar\",\"publisher\":{\"@id\":\"https:\\\/\\\/twind.io\\\/mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/twind.io\\\/mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/twind.io\\\/mx\\\/#organization\",\"name\":\"Plataforma de Gesti\u00f3n de Contratistas y Proveedores\",\"url\":\"https:\\\/\\\/twind.io\\\/mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/twind.io\\\/mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/twind.io\\\/mx\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logo-Twind.svg\",\"contentUrl\":\"https:\\\/\\\/twind.io\\\/mx\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logo-Twind.svg\",\"width\":1,\"height\":1,\"caption\":\"Plataforma de Gesti\u00f3n de Contratistas y Proveedores\"},\"image\":{\"@id\":\"https:\\\/\\\/twind.io\\\/mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/twind.io\\\/mx\\\/#\\\/schema\\\/person\\\/6c97e4770a14bee4d5d19e5239e742eb\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/twind.io\\\/cl\\\/\"],\"url\":\"https:\\\/\\\/twind.io\\\/mx\\\/author\\\/rrios_6eq9khcx\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"6 razones para eliminar las hojas de c\u00e1lculo de tu gesti\u00f3n de contratistas\u00a0 - Plataforma de Gesti\u00f3n de Contratistas y Proveedores","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_MX","og_type":"article","og_title":"6 razones para eliminar las hojas de c\u00e1lculo de tu gesti\u00f3n de contratistas\u00a0 - Plataforma de Gesti\u00f3n de Contratistas y Proveedores","og_description":"Muchos departamentos de Seguridad todav\u00eda se resisten a automatizar la gesti\u00f3n de contratistas. Y contin\u00faan invirtiendo largas jornadas de trabajo intentando poner orden en los Excel, hojas de c\u00e1lculo, correos electr\u00f3nicos y carpetas del servidor\u2026 sin \u00e9xito. Asumiendo as\u00ed, grandes riesgos en la gesti\u00f3n de contratistas. \u00bfCu\u00e1les son las desventajas de utilizar las hojas de [&hellip;]","og_url":"https:\/\/twind.io\/mx\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\/","og_site_name":"Plataforma de Gesti\u00f3n de Contratistas y Proveedores","article_published_time":"2024-07-01T12:37:15+00:00","article_modified_time":"2024-07-31T11:38:47+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/twind.io\/mx\/wp-content\/uploads\/2024\/07\/eliminar-hojas-excel-gestion-contratistas-1024x576-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/twind.io\/mx\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\/#article","isPartOf":{"@id":"https:\/\/twind.io\/mx\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\/"},"author":{"name":"admin","@id":"https:\/\/twind.io\/mx\/#\/schema\/person\/6c97e4770a14bee4d5d19e5239e742eb"},"headline":"6 razones para eliminar las hojas de c\u00e1lculo de tu gesti\u00f3n de contratistas\u00a0","datePublished":"2024-07-01T12:37:15+00:00","dateModified":"2024-07-31T11:38:47+00:00","mainEntityOfPage":{"@id":"https:\/\/twind.io\/mx\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\/"},"wordCount":1094,"commentCount":0,"publisher":{"@id":"https:\/\/twind.io\/mx\/#organization"},"image":{"@id":"https:\/\/twind.io\/mx\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\/#primaryimage"},"thumbnailUrl":"https:\/\/twind.io\/mx\/wp-content\/uploads\/2024\/07\/eliminar-hojas-excel-gestion-contratistas-1024x576-1.jpg","articleSection":["Contratos de Servicios Especializados"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/twind.io\/mx\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/twind.io\/mx\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\/","url":"https:\/\/twind.io\/mx\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\/","name":"6 razones para eliminar las hojas de c\u00e1lculo de tu gesti\u00f3n de contratistas\u00a0 - Plataforma de Gesti\u00f3n de Contratistas y Proveedores","isPartOf":{"@id":"https:\/\/twind.io\/mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/twind.io\/mx\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\/#primaryimage"},"image":{"@id":"https:\/\/twind.io\/mx\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\/#primaryimage"},"thumbnailUrl":"https:\/\/twind.io\/mx\/wp-content\/uploads\/2024\/07\/eliminar-hojas-excel-gestion-contratistas-1024x576-1.jpg","datePublished":"2024-07-01T12:37:15+00:00","dateModified":"2024-07-31T11:38:47+00:00","breadcrumb":{"@id":"https:\/\/twind.io\/mx\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/twind.io\/mx\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/twind.io\/mx\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\/#primaryimage","url":"https:\/\/twind.io\/mx\/wp-content\/uploads\/2024\/07\/eliminar-hojas-excel-gestion-contratistas-1024x576-1.jpg","contentUrl":"https:\/\/twind.io\/mx\/wp-content\/uploads\/2024\/07\/eliminar-hojas-excel-gestion-contratistas-1024x576-1.jpg","width":1024,"height":576},{"@type":"BreadcrumbList","@id":"https:\/\/twind.io\/mx\/6-razones-para-eliminar-las-hojas-de-calculo-de-tu-gestion-de-contratistas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/twind.io\/mx\/"},{"@type":"ListItem","position":2,"name":"6 razones para eliminar las hojas de c\u00e1lculo de tu gesti\u00f3n de contratistas\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/twind.io\/mx\/#website","url":"https:\/\/twind.io\/mx\/","name":"Plataforma de Gesti\u00f3n de Contratistas y Proveedores","description":"Simplifica y automatiza la gesti\u00f3n de contratistas desde un solo lugar","publisher":{"@id":"https:\/\/twind.io\/mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/twind.io\/mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/twind.io\/mx\/#organization","name":"Plataforma de Gesti\u00f3n de Contratistas y Proveedores","url":"https:\/\/twind.io\/mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/twind.io\/mx\/#\/schema\/logo\/image\/","url":"https:\/\/twind.io\/mx\/wp-content\/uploads\/2023\/04\/Logo-Twind.svg","contentUrl":"https:\/\/twind.io\/mx\/wp-content\/uploads\/2023\/04\/Logo-Twind.svg","width":1,"height":1,"caption":"Plataforma de Gesti\u00f3n de Contratistas y Proveedores"},"image":{"@id":"https:\/\/twind.io\/mx\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/twind.io\/mx\/#\/schema\/person\/6c97e4770a14bee4d5d19e5239e742eb","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5aa29802e80a4fc1d6e5aedb86fcdbeb4e7422dea9cfe1a43ddabea687c88661?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/twind.io\/cl\/"],"url":"https:\/\/twind.io\/mx\/author\/rrios_6eq9khcx\/"}]}},"_links":{"self":[{"href":"https:\/\/twind.io\/mx\/wp-json\/wp\/v2\/posts\/2132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/twind.io\/mx\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/twind.io\/mx\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/twind.io\/mx\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/twind.io\/mx\/wp-json\/wp\/v2\/comments?post=2132"}],"version-history":[{"count":3,"href":"https:\/\/twind.io\/mx\/wp-json\/wp\/v2\/posts\/2132\/revisions"}],"predecessor-version":[{"id":2242,"href":"https:\/\/twind.io\/mx\/wp-json\/wp\/v2\/posts\/2132\/revisions\/2242"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/twind.io\/mx\/wp-json\/wp\/v2\/media\/2133"}],"wp:attachment":[{"href":"https:\/\/twind.io\/mx\/wp-json\/wp\/v2\/media?parent=2132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/twind.io\/mx\/wp-json\/wp\/v2\/categories?post=2132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/twind.io\/mx\/wp-json\/wp\/v2\/tags?post=2132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}